{"id":19282,"date":"2023-10-04T08:09:44","date_gmt":"2023-10-04T11:09:44","guid":{"rendered":"https:\/\/radiobitacora.com.ar\/web\/?p=19282"},"modified":"2023-10-04T08:09:44","modified_gmt":"2023-10-04T11:09:44","slug":"el-gobierno-publico-el-decreto-para-que-ana-maria-figueroa-siga-siendo-jueza-por-cinco-anos-mas","status":"publish","type":"post","link":"https:\/\/radiobitacora.com.ar\/web\/2023\/10\/04\/el-gobierno-publico-el-decreto-para-que-ana-maria-figueroa-siga-siendo-jueza-por-cinco-anos-mas\/","title":{"rendered":"El Gobierno public\u00f3 el decreto para que Ana Mar\u00eda Figueroa siga siendo jueza por cinco a\u00f1os m\u00e1s"},"content":{"rendered":"<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">Luego que el oficialismo lograra aprobar en el Senado el pliego de<b>\u00a0Ana Mar\u00eda Figueroa<\/b>, el Gobierno Nacional public\u00f3 el decreto para que contin\u00fae siendo jueza por cinco a\u00f1os m\u00e1s.<\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\"><b>\u201cN\u00f3mbrase, por el t\u00e9rmino de CINCO (5) a\u00f1os a partir del 9 de agosto de 2023, VOCAL DE LA C\u00c1MARA FEDERAL DE CASACI\u00d3N PENAL a la doctora Ana Mar\u00eda FIGUEROA (D.N.I. N\u00ba 4.677.857), quien oportunamente fue nombrada por el PODER EJECUTIVO NACIONAL para desempe\u00f1ar dicho cargo<\/b>\u00a0mediante el Decreto N\u00b0 1896 del 21 de noviembre de 2011 y trasladada mediante el Decreto N\u00b0 143 del 4 de febrero de 2013\u2033, reza el\u00a0<b>Decreto 502\/2023<\/b>\u00a0comunicado esta madrugada en el\u00a0<b>Bolet\u00edn Oficial<\/b>\u00a0y que cont\u00f3 con las firmas del presidente\u00a0<b>Alberto Fern\u00e1ndez<\/b>, del jefe de Gabinete\u00a0<b>Agust\u00edn Rossi\u00a0<\/b>y del ministro de Justicia,\u00a0<b>Mart\u00edn Soria<\/b>.<\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">El jueves de la semana pasada, tras un doble empate en la votaci\u00f3n,\u00a0<b>Claudia Ledesma Abdala\u00a0<\/b>\u2014Presidenta provisional de la C\u00e1mara\u2014 fue quien defini\u00f3 para que el Senado aprobara el pliego de Figueroa. Con 70 senadores en sus bancas, el resultado de la votaci\u00f3n fue de<b>\u00a035 a 35\u00a0<\/b>\u2014dos veces\u2014. Ante esto, por reglamento tuvo que desempatar la santiague\u00f1a, que presid\u00eda la sesi\u00f3n ante la ausencia de Cristina Kirchner.<\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">Tras la aprobaci\u00f3n en la C\u00e1mara Alta, solo faltaba la publicaci\u00f3n del decreto que firm\u00f3 Alberto Fern\u00e1ndez en la tarde de este martes.<\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">La Corte Suprema de Justicia hab\u00eda definido que se deb\u00eda jubilar de la Sala 1 de la C\u00e1mara de Casaci\u00f3n Penal de Justicia el pasado 9 de agosto cuando cumpli\u00f3 los 75 a\u00f1os de edad, el l\u00edmite que fija la Constituci\u00f3n Nacional. Por eso el kirchnerismo buscaba aprobar el pliego antes de dicha fecha, sin embargo Juntos por el Cambio logr\u00f3 bloquear varios de los intentos que hizo el interbloque del Frente de Todos. Sin embargo, el oficialismo logr\u00f3 sumar a otros bloques, obtuvo el qu\u00f3rum y avanz\u00f3.<\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">Figueroa\u00a0<b>ten\u00eda que resolver los expedientes \u201cLos Sauces &#8211; Hotesur\u201d y la firma del memor\u00e1ndum de entendimiento con Ir\u00e1n en los que est\u00e1 involucrada la vicepresidenta de la Naci\u00f3n, Cristina Kirchner<\/b>. Justamente \u2014tras la salida de la jueza\u2014 la Sala I de Casaci\u00f3n resolvi\u00f3 reabrir ambas causas. Son dos expedientes que se hab\u00edan cerrado en 2021 en los dos tribunales orales que ten\u00edan que hacer el juicio diciendo que no hab\u00eda delito. Apelaciones mediante, Casaci\u00f3n, resolvi\u00f3 avanzar hacia juicio oral para que se resolviera all\u00ed.<\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">Tras el cese de actividades de Figueroa notificado por la Corte Suprema,<b>\u00a0a principios de septiembre<\/b>\u00a0tambi\u00e9n se resolvi\u00f3 que la presidencia de la C\u00e1mara Federal de Casaci\u00f3n quede en manos de Mariano Borinsky, la vicepresidencia de Daniel Petrone y la segunda presidencia de Diego Barroetave\u00f1a.<\/p>\n<div class=\"visual__image\"><img loading=\"lazy\" decoding=\"async\" class=\" lazyload\" src=\"https:\/\/www.infobae.com\/new-resizer\/coCUGfUgnYNHTwNS54pbb9vWqBM=\/arc-anglerfish-arc2-prod-infobae\/public\/ZN2SGBI25ZDLLESJ77DWTRRIEM.jpg\" sizes=\"auto, (min-width: 800px) 50vw, 90vw\" srcset=\"https:\/\/www.infobae.com\/new-resizer\/kuDh-QBu8_E8NBEMc0dhuLsEy2Q=\/420x280\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/ZN2SGBI25ZDLLESJ77DWTRRIEM.jpg 420w,https:\/\/www.infobae.com\/new-resizer\/J5oFgTP7Zulfqy6a8jC0g0jsY4k=\/768x512\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/ZN2SGBI25ZDLLESJ77DWTRRIEM.jpg 768w,https:\/\/www.infobae.com\/new-resizer\/N9Hmvlgj1YH4sNKMKGY_o-xLt5o=\/992x661\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/ZN2SGBI25ZDLLESJ77DWTRRIEM.jpg 992w,https:\/\/www.infobae.com\/new-resizer\/on1Ebyyi31WYpzRu0WJJlaQiTC4=\/1200x800\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/ZN2SGBI25ZDLLESJ77DWTRRIEM.jpg 1200w,https:\/\/www.infobae.com\/new-resizer\/3P5EFVXxGdg6KE-dWZE1NZTYEtI=\/1440x960\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/ZN2SGBI25ZDLLESJ77DWTRRIEM.jpg 1440w\" alt=\"El decreto cuenta con la firma del presidente Alberto Fern\u00e1ndez\" width=\"1920\" height=\"1280\" data-src=\"https:\/\/www.infobae.com\/new-resizer\/coCUGfUgnYNHTwNS54pbb9vWqBM=\/arc-anglerfish-arc2-prod-infobae\/public\/ZN2SGBI25ZDLLESJ77DWTRRIEM.jpg\" \/>El decreto cuenta con la firma del presidente Alberto Fern\u00e1ndez<\/div>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">En este escenario judicial y tras la definici\u00f3n de Casaci\u00f3n respecto a la reapertura de las dos causas citadas, la vicepresidenta de la Naci\u00f3n pidi\u00f3 que se declaren nulos los fallos de la C\u00e1mara Federal de Casaci\u00f3n Penal que revocaron sus sobreseimientos y<b>\u00a0ordenaron que se hagan los juicios orales en las causas \u201cLos Sauces-Hotesur\u201d y la firma del memor\u00e1ndum<\/b>\u00a0de entendimiento con Ir\u00e1n. La defensa de la ex presidenta plante\u00f3, entre otros argumentos, que las resoluciones fueron dictadas justamente sin la intervenci\u00f3n de la jueza Ana Mar\u00eda Figueroa, que fue cesanteada por la Corte Suprema de Justicia de la Naci\u00f3n por llegar a los 75 a\u00f1os \u2014la edad m\u00e1xima que establece la Constituci\u00f3n Nacional\u2014 sin contar con un nuevo acuerdo del Senado, que lo obtuvo la semana pasada.<\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">El oficialismo en la C\u00e1mara Alta vot\u00f3 por el regreso de Figueroa y Alberto Fern\u00e1ndez lo convalid\u00f3. La decisi\u00f3n sobre las apelaciones de los implicados en la causa del Memor\u00e1dum ser\u00e1 revisada por la Corte Suprema. El procurador del Tesoro Carlos Zannini est\u00e1 pidiendo el apartamiento de sus integrantes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Luego que el oficialismo lograra aprobar en el Senado el pliego de\u00a0Ana Mar\u00eda Figueroa, el Gobierno Nacional public\u00f3 el decreto para que contin\u00fae siendo jueza por cinco a\u00f1os m\u00e1s. \u201cN\u00f3mbrase, por el t\u00e9rmino de CINCO (5) a\u00f1os a partir del 9 de agosto de 2023, VOCAL DE LA C\u00c1MARA FEDERAL DE CASACI\u00d3N PENAL a la [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":19283,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[79],"tags":[],"class_list":["post-19282","post","type-post","status-publish","format-standard","has-post-thumbnail","category-politica"],"_links":{"self":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/posts\/19282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/comments?post=19282"}],"version-history":[{"count":0,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/posts\/19282\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/media\/19283"}],"wp:attachment":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/media?parent=19282"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/categories?post=19282"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/tags?post=19282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}