{"id":20494,"date":"2024-02-02T09:28:15","date_gmt":"2024-02-02T12:28:15","guid":{"rendered":"https:\/\/radiobitacora.com.ar\/web\/?p=20494"},"modified":"2024-02-02T09:28:15","modified_gmt":"2024-02-02T12:28:15","slug":"privatizaciones-y-facultades-delegadas-cuales-son-los-cambios-que-propuso-el-gobierno-para-acercar-posiciones","status":"publish","type":"post","link":"https:\/\/radiobitacora.com.ar\/web\/2024\/02\/02\/privatizaciones-y-facultades-delegadas-cuales-son-los-cambios-que-propuso-el-gobierno-para-acercar-posiciones\/","title":{"rendered":"Privatizaciones y facultades delegadas: cu\u00e1les son los cambios que propuso el Gobierno para acercar posiciones"},"content":{"rendered":"<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">Durante el segundo d\u00eda de debate de la\u00a0<b>Ley \u00d3mnibus\u00a0<\/b>en la C\u00e1mara de Diputados, el Gobierno envi\u00f3\u00a0<b>un nuevo texto<\/b>\u00a0con modificaciones para destrabar dos de los puntos que corr\u00edan riesgo de caer rechazados:\u00a0<b>privatizaciones y facultades delegadas.<\/b><\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">La nueva redacci\u00f3n, que incluye varios art\u00edculos nuevos, atiende muchos de los planteos de la oposici\u00f3n dialoguista. En el caso de las privatizaciones,\u00a0<b>el listado final de empresas que pueden ser vendidas baj\u00f3 de 39 a 30.<\/b>\u00a0Estas incluyen\u00a0<b>tres\u00a0<\/b>empresas que solo podr\u00e1n ser\u00a0<b>privatizadas parcialmente<\/b>:\u00a0<b>Banco Naci\u00f3n, Nucleoel\u00e9ctrica Argentina y ARSAT<\/b>, muy resistidas por la oposici\u00f3n dado que son consideradas estrat\u00e9gicas.<\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">Entre las empresas que\u00a0<b>quedaron fuera<\/b> de la lista se destacan Fabricaciones Militares, Banco de Inversi\u00f3n y Comercio Exterior (BICE), Dioxitek, F\u00e1brica Argentina de Aviones, Casa de Moneda, Radio Nacional de Universidad del Litoral, Servicio de Radio y Televisi\u00f3n de la Universidad de C\u00f3rdoba, Veh\u00edculo Espacial Nueva Generaci\u00f3n y Yacimiento Minero de Agua de Dionisio.<\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">Por otro lado, el nuevo cap\u00edtulo se divide en<b>\u00a0tres art\u00edculos<\/b>, con sus\u00a0<b>respectivos anexos<\/b>, con listados de empresas sujetas a privatizaci\u00f3n total y\u00a0<b>uno de privatizaciones parciales<\/b>. Esta divisi\u00f3n puede facilitar que la oposici\u00f3n pueda\u00a0<b>votar negativamente en casos acotados<\/b>, sin hacer caer todo el paquete. Por lo tanto, se acerca a la posici\u00f3n de quienes propon\u00edan aprobar \u201cempresa por empresa\u201d las privatizaciones.<\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">Para reforzar la transparencia del proceso de privatizaci\u00f3n, una\u00a0<b>Comisi\u00f3n Bicameral<\/b>\u00a0compuesta por seis diputados y seis senadores deber\u00e1 ser informada por el Ejecutivo de la modalidad y el procedimiento escogido para vender las empresas, del pliego de condiciones 15 d\u00edas antes de su publicaci\u00f3n y cualquier circunstancia relevante que se produzca. En tanto, se\u00f1ala que la Sindicatura General de la Naci\u00f3n (<b>SIGEN<\/b>) y la Auditor\u00eda General de la Naci\u00f3n (<b>AGN<\/b>) actuar\u00e1n en colaboraci\u00f3n permanente con la bicameral.<\/p>\n<div class=\"news-module\" data-mrf-recirculation=\"IL_-wd-gci6QsulDJBntUpS5Q\" data-testid=\"text-html\" data-mrf-experience=\"IL_-wd-gci6QsulDJBntUpS5Q\">\n<div class=\"recommended-card__image-container\"><\/div>\n<\/div>\n<div class=\"visual__image\"><img loading=\"lazy\" decoding=\"async\" class=\" lazyload\" src=\"https:\/\/www.infobae.com\/new-resizer\/2Xuqf_mZqH8SW1rbBd5jP34QSzI=\/420x236\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/S6TSZAQVQFAYXHTGL7BNABZOOM.jpg%20420w\" sizes=\"auto, (min-width: 1560px) 856px, (min-width: 1000px) calc(74.63vw - 293px), (min-width: 780px) calc(100vw - 376px), (min-width: 580px) calc(100vw - 32px), 100vw\" srcset=\"https:\/\/www.infobae.com\/new-resizer\/2Xuqf_mZqH8SW1rbBd5jP34QSzI=\/420x236\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/S6TSZAQVQFAYXHTGL7BNABZOOM.jpg 420w,https:\/\/www.infobae.com\/new-resizer\/iIwWvBrlnoKvmqnfvnHNhESyHs4=\/768x432\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/S6TSZAQVQFAYXHTGL7BNABZOOM.jpg 768w,https:\/\/www.infobae.com\/new-resizer\/Q9_3O8HajSxiPxOoBIhhBsJEwjs=\/992x558\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/S6TSZAQVQFAYXHTGL7BNABZOOM.jpg 992w,https:\/\/www.infobae.com\/new-resizer\/9LSqrVTAjfXg1IEH9txNJiB2E40=\/1200x675\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/S6TSZAQVQFAYXHTGL7BNABZOOM.jpg 1200w,https:\/\/www.infobae.com\/new-resizer\/leOo7BUg2SFoghx2-iWaIPOUHj0=\/1440x810\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/S6TSZAQVQFAYXHTGL7BNABZOOM.jpg 1440w\" alt=\"Mart\u00edn Menem conversa con diputados de la oposici\u00f3n en pleno debate\" width=\"1920\" height=\"1080\" data-src=\"https:\/\/www.infobae.com\/new-resizer\/2Xuqf_mZqH8SW1rbBd5jP34QSzI=\/420x236\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/S6TSZAQVQFAYXHTGL7BNABZOOM.jpg 420w\" \/>Mart\u00edn Menem conversa con diputados de la oposici\u00f3n en pleno debate<\/div>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">Adem\u00e1s, antes de que se inicie el proceso de privatizaci\u00f3n la\u00a0<b>Secretar\u00eda de Empresas y Sociedades del Estado<\/b>\u00a0de la Jefatura de Gabinete de Ministros, en coordinaci\u00f3n con el\u00a0<b>Sindicatura General de la Naci\u00f3n,<\/b>\u00a0deber\u00e1 elaborar y hacer p\u00fablico un\u00a0<b>informe integral\u00a0<\/b>sobre la empresa que contendr\u00e1 informaci\u00f3n detallada sobre sus aspectos patrimoniales, econ\u00f3micos, financieros, y operativos. Este informe deber\u00e1 ser remitido a la Comisi\u00f3n Bicameral.<\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">En cuanto a las emergencias y las facultades delegadas, desde los sectores dialoguistas reconocieron que las posiciones se acercaron cuando el oficialismo\u00a0<b>elimin\u00f3 la emergencia fiscal y previsional.<\/b><\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">El proyecto declara la emergencia p\u00fablica en\u00a0<b>materia econ\u00f3mica, financiera, de seguridad, tarifaria, energ\u00e9tica y administrativa<\/b>\u00a0hasta el 31 de diciembre de 2024. Este plazo podr\u00e1 ser prorrogado por el Congreso por el plazo m\u00e1ximo de un a\u00f1o.<\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">Por otro lado, el oficialismo decidi\u00f3 mantener -en el art\u00edculo 73- la derogaci\u00f3n del art\u00edculo 1 de la Ley de Fortalecimiento de la sostenibilidad de la deuda p\u00fablica (N\u00b0 27.612), conocida como \u201cLey Guzm\u00e1n\u201d, que pon\u00eda<b>\u00a0l\u00edmites a la toma de deuda en d\u00f3lares<\/b>\u00a0con legislaci\u00f3n extranjera. Sin acuerdo con el\u00a0<b>radicalismo\u00a0<\/b>y\u00a0<b>HCF<\/b>, ese punto se encamina a ser rechazado ya que defienden la potestad del Congreso de controlar al Ejecutivo.<\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">Tras la segunda jornada de debate se lleg\u00f3 a un nuevo cuarto intermedio y\u00a0<b>la sesi\u00f3n se reanudar\u00e1 este viernes a las 10 de la ma\u00f1ana<\/b>. Pasada la medianoche, el oficialismo propuso interrumpir la discusi\u00f3n parlamentaria, mientras contin\u00faan negociando los art\u00edculos clave sobre los que a\u00fan no hay acuerdo, como la<b>\u00a0potestad de tomar y reestructurar deuda y los cambios en seguridad<\/b>, adem\u00e1s de los anteriormente mencionados. En efecto, pese a las modificaciones planteadas, un sector de diputados radicales referenciados en Facundo Manes se mantiene firme en el rechazo de facultades delegadas y pretende que las privatizaciones se debatan \u201cley por ley\u201d en el Congreso.<\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">En la misma sinton\u00eda, la Coalici\u00f3n C\u00edvica se muestra inflexible sobre las facultades delegadas. En cambio, en Hacemos Coalici\u00f3n Federal se dio libertad de acci\u00f3n a la hora de la votaci\u00f3n en particular. Por \u00faltimo, los diputados de\u00a0<b>C\u00f3rdoba Federal<\/b>, que responden al gobernador Mart\u00edn Llaryora, siguen amenazando con restar apoyos si no se atiene a los reclamos de los mandatarios provinciales, a los que el Gobierno prometi\u00f3 un nuevo pacto fiscal.<\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">El debate continuar\u00e1 con m\u00e1s de 30 oradores y estiman que<b>\u00a0la votaci\u00f3n en general ser\u00e1 hoy cerca de las 14<\/b>. En las filas de la oposici\u00f3n entienden que el Gobierno opt\u00f3 por postergar la votaci\u00f3n en general para continuar negociando y para no correr el riesgo de no poder volver a reunir el qu\u00f3rum para la votaci\u00f3n en particular.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante el segundo d\u00eda de debate de la\u00a0Ley \u00d3mnibus\u00a0en la C\u00e1mara de Diputados, el Gobierno envi\u00f3\u00a0un nuevo texto\u00a0con modificaciones para destrabar dos de los puntos que corr\u00edan riesgo de caer rechazados:\u00a0privatizaciones y facultades delegadas. La nueva redacci\u00f3n, que incluye varios art\u00edculos nuevos, atiende muchos de los planteos de la oposici\u00f3n dialoguista. En el caso de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":20495,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[79],"tags":[],"class_list":["post-20494","post","type-post","status-publish","format-standard","has-post-thumbnail","category-politica"],"_links":{"self":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/posts\/20494","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/comments?post=20494"}],"version-history":[{"count":0,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/posts\/20494\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/media\/20495"}],"wp:attachment":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/media?parent=20494"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/categories?post=20494"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/tags?post=20494"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}