{"id":23000,"date":"2024-12-05T09:34:54","date_gmt":"2024-12-05T12:34:54","guid":{"rendered":"https:\/\/radiobitacora.com.ar\/web\/?p=23000"},"modified":"2024-12-05T09:34:54","modified_gmt":"2024-12-05T12:34:54","slug":"la-justicia-paraguaya-va-a-fondo-con-un-equipo-de-tres-fiscales-para-investigar-a-kueider","status":"publish","type":"post","link":"https:\/\/radiobitacora.com.ar\/web\/2024\/12\/05\/la-justicia-paraguaya-va-a-fondo-con-un-equipo-de-tres-fiscales-para-investigar-a-kueider\/","title":{"rendered":"La justicia paraguaya va a fondo, con un equipo de tres fiscales para investigar a Kueider"},"content":{"rendered":"<p>La justicia de Paraguay cre\u00f3 un equipo especial de fiscales para investigar el caso del senador Edgardo Kueider, por los presuntos delitos de lavado de activos y contrabando, tras ser detenido en ese pa\u00eds con m\u00e1s de 200 mil d\u00f3lares, pesos argentinos y guaran\u00edes no declarados.<\/p>\n<div class=\"container-spot\" data-tipo=\"tipo_todo\" data-pos=\"NEW_P1_cuerpo\"><\/div>\n<p>Inicialmente, el caso qued\u00f3 a cargo del fiscal de Contrabando, Edgar Ben\u00edtez, pero en las \u00faltimas horas se sumaron Alcides Gim\u00e9nez Zorrilla y Gabriel Segovia Villasanti para decidir el futuro procesal del legislador entrerriano.<\/p>\n<p>En la resoluci\u00f3n del Ministerio P\u00fablico Fiscal de Paraguay, a la que tuvo acceso TN, el fiscal adjunto Jorge Sosa Garc\u00eda especific\u00f3 que \u201cse hace imperiosa la conformaci\u00f3n de un equipo de trabajo o coadyuvancia a intervenir en prosecuci\u00f3n de las pesquisas en el marco de los autos objeto de investigaci\u00f3n, atendiendo la complejidad y las exigencias investigativas a ser desplegadas\u201d.<\/p>\n<div class=\"container-spot\" data-tipo=\"tipo_todo\" data-pos=\"NEW_P2_cuerpo\"><\/div>\n<p>Ben\u00edtez dijo en medios paraguayos que la detenci\u00f3n de Kueider se dispuso con el fin de garantizar la continuidad del procedimiento legal. Luego de la declaraci\u00f3n del senador y de su acompa\u00f1ante, se dispuso que el legislador quede preso en Paraguay tras ser imputado formalmente en el caso.<\/p>\n<p><strong>El abogado del legislador dijo que el dinero no era de Kueider<\/strong><br \/>\nC\u00e9sar Nider Centuri\u00f3n, abogado de Kueider, asegur\u00f3 que el dinero es propiedad de una empresa para la que trabaja Iara Magdalena Guinsel Costa, secretaria del senador, que tambi\u00e9n qued\u00f3 detenida. \u201cEllos se presentaron voluntariamente a hacer su descargo\u201d, dijo.<\/p>\n<div class=\"container-spot\" data-tipo=\"tipo_todo\" data-pos=\"NEW_P3_cuerpo\"><\/div>\n<p>Y agreg\u00f3: \u201cLa se\u00f1ora trabaja en una empresa paraguaya, en una sociedad an\u00f3nima. Es apoderada general y hace gestiones para esa empresa. Dentro de su \u00e1mbito de gesti\u00f3n est\u00e1 la adquisici\u00f3n de mercader\u00edas en Ciudad del Este, como electr\u00f3nica, perfumes, cosm\u00e9ticos. El dinero se le entreg\u00f3 para ese fin\u201d. Seg\u00fan el abogado, recibi\u00f3 el dinero cuando llegaron a la ciudad fronteriza.<\/p>\n<p>Seg\u00fan el relato del abogado, como el restaurante del hotel donde se hospedaban ya estaba cerrado, decidieron ir a cenar a la ciudad brasilera de Foz de Iguaz\u00fa y llevar los billetes encima por cuestiones de seguridad. \u201cNo quiso dejarlo en el hotel, por eso fueron a Foz de Iguaz\u00fa\u201d, relat\u00f3 Centuri\u00f3n. Respecto del v\u00ednculo de Costa con Kueider, solo mencion\u00f3 que \u201cella es allegada del senador, vive en Asunci\u00f3n, pero es argentina\u201d.<\/p>\n<div class=\"container-spot\" data-tipo=\"tipo_todo\" data-pos=\"NEW_P4_cuerpo\"><\/div>\n<p>Sobre el auto decomisado, el representante legal especific\u00f3 que \u201ces de un ciudadano argentino, pero la se\u00f1orita tiene un poder que se le extendi\u00f3 en Buenos Aires para conducir en territorio argentino y paraguayo\u201d.<\/p>\n<p>El legislador se encontraba este mi\u00e9rcoles en Ciudad del Este cuando decidi\u00f3 cruzar a Brasil para ir a cenar. Al volver fue retenido por un control fronterizo en el que se verific\u00f3 que llevaba d\u00f3lares, guaran\u00edes y pesos argentinos, que no estaban declarados.<\/p>\n<div class=\"container-spot\" data-tipo=\"tipo_todo\" data-pos=\"NEW_P5_cuerpo\"><\/div>\n<p><strong>Kueider pedir\u00e1 licencia en su cargo mientras se investigue su situaci\u00f3n<\/strong><br \/>\nA trav\u00e9s de un comunicado, el senador nacional Edgardo Kueider inform\u00f3 que tom\u00f3 la decisi\u00f3n de pedir licencia a su cargo como senador.<\/p>\n<p>Afirm\u00f3 que \u201csu determinaci\u00f3n tiene como objetivo que no haya ning\u00fan tipo de impedimento\u201d a la hora de que se lo investigue. De este modo, espera que se pongan en marcha \u201ctodos los mecanismos institucionales correspondientes y que se aclaren los hechos\u201d.<\/p>\n<div class=\"container-spot\" data-tipo=\"tipo_todo\" data-pos=\"NEW_P6_cuerpo\"><\/div>\n<p>El bloque Las Provincias Unidas, al que pertenece Kueider, manifest\u00f3 que \u201ctodos los funcionarios p\u00fablicos deben someterse a la Justicia\u201d. Presidido por Carlos \u201cCamau\u201d Esp\u00ednola, el grupo incluye a legisladores que se definen como \u201cperonistas no kirchneristas\u201d. Sin embargo, su rol clave en la aprobaci\u00f3n de la Ley Bases y el paquete fiscal lo hab\u00eda acercado al oficialismo en votaciones ajustadas.<\/p>\n<p>La expresidenta Cristina Kirchner calific\u00f3 a Kueider como un \u201cperonista que pas\u00f3 a votar como libertario\u201d y respald\u00f3 el pedido de expulsi\u00f3n presentado por senadores de su interbloque. La solicitud, firmada por Jos\u00e9 Mayans, Juliana Di Tullio y Anabel Fern\u00e1ndez Sagasti, argumenta una \u201cinhabilidad moral sobreviniente\u201d y busca preservar la integridad institucional del Senado.<\/p>\n<div class=\"container-spot\" data-tipo=\"tipo_todo\" data-pos=\"NEW_P7_cuerpo\"><\/div>\n<p>Desde el oficialismo, se apresuraron a desvincularse del esc\u00e1ndalo. El presidente Javier Milei afirm\u00f3: \u201cLo de Kueider es un problema del kirchnerismo, no de nuestro gobierno\u201d. En tanto, la vicepresidenta Victoria Villarruel carg\u00f3 contra Cristina Kirchner, recordando que Kueider fue electo en 2019 bajo su liderazgo: \u201cIntentar ensuciar requiere estar limpia, y usted no lo est\u00e1\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La justicia de Paraguay cre\u00f3 un equipo especial de fiscales para investigar el caso del senador Edgardo Kueider, por los presuntos delitos de lavado de activos y contrabando, tras ser detenido en ese pa\u00eds con m\u00e1s de 200 mil d\u00f3lares, pesos argentinos y guaran\u00edes no declarados. Inicialmente, el caso qued\u00f3 a cargo del fiscal de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":23001,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[79],"tags":[],"class_list":["post-23000","post","type-post","status-publish","format-standard","has-post-thumbnail","category-politica"],"_links":{"self":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/posts\/23000","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/comments?post=23000"}],"version-history":[{"count":0,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/posts\/23000\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/media\/23001"}],"wp:attachment":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/media?parent=23000"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/categories?post=23000"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/tags?post=23000"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}