{"id":27693,"date":"2025-11-18T09:20:39","date_gmt":"2025-11-18T12:20:39","guid":{"rendered":"https:\/\/radiobitacora.com.ar\/web\/?p=27693"},"modified":"2025-11-18T09:20:39","modified_gmt":"2025-11-18T12:20:39","slug":"goya-recordo-a-las-victimas-de-siniestros-viales-con-una-misa-y-acciones-de-concientizacion","status":"publish","type":"post","link":"https:\/\/radiobitacora.com.ar\/web\/2025\/11\/18\/goya-recordo-a-las-victimas-de-siniestros-viales-con-una-misa-y-acciones-de-concientizacion\/","title":{"rendered":"GOYA RECORD\u00d3 A LAS V\u00cdCTIMAS DE SINIESTROS VIALES CON UNA MISA Y ACCIONES DE CONCIENTIZACI\u00d3N"},"content":{"rendered":"<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">En el marco del D\u00eda Mundial en Recuerdo de las V\u00edctimas de Siniestros Viales, que cada a\u00f1o se conmemora el tercer domingo de noviembre, la comunidad de Goya se reuni\u00f3 este domingo por la noche para rendir homenaje a quienes perdieron la vida en hechos viales y renovar el compromiso con la prevenci\u00f3n.<\/p>\n<p style=\"font-weight: 400;\">La Iglesia \u201cNuestra Se\u00f1ora del Rosario\u201d fue el escenario de una emotiva misa celebrada a las 20:30, donde familiares, amigos y vecinos llegaron con profundo respeto y recogimiento. La ceremonia celebrada por el p\u00e1rroco Ariel Gim\u00e9nez cont\u00f3 con la presencia del Director de Tr\u00e1nsito de la Municipalidad de Goya, licenciado Alejandro Stortti acompa\u00f1ado por Viviana Canaparro, referente de la organizaci\u00f3n Estrellas Amarillas, junto a familiares de v\u00edctimas de siniestros viales, quienes participaron activamente del acto.<\/p>\n<p style=\"font-weight: 400;\">Tras la misa, los presentes se trasladaron frente a plaza Mitre, donde se realiz\u00f3 la tradicional prenda de velas, un gesto simb\u00f3lico que ilumin\u00f3 la noche y puso de manifiesto la necesidad de mantener viva la memoria de quienes ya no est\u00e1n.<\/p>\n<p style=\"font-weight: 400;\">CONCIENTIZACI\u00d3N Y TRABAJO CONJUNTO<\/p>\n<p style=\"font-weight: 400;\">En el marco de esta fecha, la ONG Estrellas Amarillas reforz\u00f3 su llamado a la responsabilidad vial y a la importancia de transformar el dolor en acciones preventivas. En colaboraci\u00f3n con la Direcci\u00f3n de Tr\u00e1nsito, se programaron diversas actividades destinadas a involucrar a las familias y difundir h\u00e1bitos seguros al momento de circular por la v\u00eda p\u00fablica.<\/p>\n<p style=\"font-weight: 400;\">UN MENSAJE QUE INTERPELA<\/p>\n<p style=\"font-weight: 400;\">Cada vela encendida, cada nombre recordado y cada abrazo compartido en la Catedral de Goya reafirmaron el sentido profundo de esta fecha. M\u00e1s all\u00e1 de la conmemoraci\u00f3n, la jornada dej\u00f3 un mensaje contundente: la vida es un bien precioso que debe ser cuidado entre todos. La memoria de las v\u00edctimas impulsa, una vez m\u00e1s, a redoblar esfuerzos para construir un tr\u00e1nsito m\u00e1s seguro, responsable y humano.<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">Direcci\u00f3n de Prensa \u2013 Municipalidad de Goya.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el marco del D\u00eda Mundial en Recuerdo de las V\u00edctimas de Siniestros Viales, que cada a\u00f1o se conmemora el tercer domingo de noviembre, la comunidad de Goya se reuni\u00f3 este domingo por la noche para rendir homenaje a quienes perdieron la vida en hechos viales y renovar el compromiso con la prevenci\u00f3n. La Iglesia [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":27694,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56],"tags":[],"class_list":["post-27693","post","type-post","status-publish","format-standard","has-post-thumbnail","category-locales"],"_links":{"self":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/posts\/27693","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/comments?post=27693"}],"version-history":[{"count":0,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/posts\/27693\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/media\/27694"}],"wp:attachment":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/media?parent=27693"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/categories?post=27693"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/tags?post=27693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}