{"id":27894,"date":"2025-11-24T20:43:33","date_gmt":"2025-11-24T23:43:33","guid":{"rendered":"https:\/\/radiobitacora.com.ar\/web\/?p=27894"},"modified":"2025-11-24T20:48:50","modified_gmt":"2025-11-24T23:48:50","slug":"goya-abrio-sus-puertas-de-la-historia-la-cultura-el-arte-la-musica-la-literatura-y-el-turismo","status":"publish","type":"post","link":"https:\/\/radiobitacora.com.ar\/web\/2025\/11\/24\/goya-abrio-sus-puertas-de-la-historia-la-cultura-el-arte-la-musica-la-literatura-y-el-turismo\/","title":{"rendered":"GOYA ABRI\u00d3 SUS PUERTAS DE LA HISTORIA, LA CULTURA, EL ARTE, LA M\u00daSICA, LA LITERATURA Y EL TURISMO"},"content":{"rendered":"<p style=\"font-weight: 400;\">\u201cLA NOCHE DE LOS MUSEOS\u201d<\/p>\n<p style=\"font-weight: 400;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-27895\" src=\"https:\/\/radiobitacora.com.ar\/web\/wp-content\/uploads\/2025\/11\/Noche-de-los-Museos-en-Goya-6.jpg\" alt=\"\" width=\"1600\" height=\"1066\" srcset=\"https:\/\/radiobitacora.com.ar\/web\/wp-content\/uploads\/2025\/11\/Noche-de-los-Museos-en-Goya-6.jpg 1600w, https:\/\/radiobitacora.com.ar\/web\/wp-content\/uploads\/2025\/11\/Noche-de-los-Museos-en-Goya-6-630x420.jpg 630w, https:\/\/radiobitacora.com.ar\/web\/wp-content\/uploads\/2025\/11\/Noche-de-los-Museos-en-Goya-6-696x464.jpg 696w, https:\/\/radiobitacora.com.ar\/web\/wp-content\/uploads\/2025\/11\/Noche-de-los-Museos-en-Goya-6-1068x712.jpg 1068w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/p>\n<p style=\"font-weight: 400;\">Un itinerario propuesto para recorrer los lugares ic\u00f3nicos y emblem\u00e1ticos de la ciudad de Goya, rescatando gracias al aporte de los gu\u00edas urbanos y de sitio la riqueza patrimonial de la ciudad.<\/p>\n<p style=\"font-weight: 400;\">La iniciativa el s\u00e1bado dio inicio pasadas las 18 y 30 horas con la partida del \u201ccolectivo\u201d dispuesto para aquellas personas que optaron por el City Tour, completando la capacidad de la unidad dispuesta para cumplir con el objetivo, sum\u00e1ndose aquellos que de manera particular e independiente realizaron ese circuito establecido.<\/p>\n<p style=\"font-weight: 400;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-27896\" src=\"https:\/\/radiobitacora.com.ar\/web\/wp-content\/uploads\/2025\/11\/Noche-de-los-Museos-en-Goya-2.jpg\" alt=\"\" width=\"1600\" height=\"1066\" srcset=\"https:\/\/radiobitacora.com.ar\/web\/wp-content\/uploads\/2025\/11\/Noche-de-los-Museos-en-Goya-2.jpg 1600w, https:\/\/radiobitacora.com.ar\/web\/wp-content\/uploads\/2025\/11\/Noche-de-los-Museos-en-Goya-2-630x420.jpg 630w, https:\/\/radiobitacora.com.ar\/web\/wp-content\/uploads\/2025\/11\/Noche-de-los-Museos-en-Goya-2-696x464.jpg 696w, https:\/\/radiobitacora.com.ar\/web\/wp-content\/uploads\/2025\/11\/Noche-de-los-Museos-en-Goya-2-1068x712.jpg 1068w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/p>\n<p style=\"font-weight: 400;\">Punto de partida del circuito en el Cementerio La Soledad, valorando el enorme trabajo profesional de los gu\u00edas que han permitido \u201crecobrar la vida y la historia\u201d de los personajes y personalidades ilustradas en sus relatos, captando en cada visita la atenci\u00f3n de los \u201cvisitante\u201d donde se puede mencionar como un hecho novedoso por la incorporaci\u00f3n del espacio y la recreaci\u00f3n del \u00e1mbito el Hotel de Los Inmigrantes, adecuado para darle sentido de espera para \u201calbergar\u201d en sus habitaciones a los turistas, una excelente recreaci\u00f3n que posibilit\u00f3 comprender la utilidad de ese edificio en la \u00e9poca de receptividad de aquellos que optaban por este suelo para desarrollar sus actividades y planificar su porvenir.<\/p>\n<p style=\"font-weight: 400;\">El circuito prosigui\u00f3 con la visita a lugares tradicionales como los Museos Sanmartiniano, de la Ciudad, la nueva inclusi\u00f3n de sitios el Instituto Artmake, de maquetas, arribando el contingente a la Iglesia La Rotonda para recorrer a trav\u00e9s de la explicaci\u00f3n del gu\u00eda de sitio la Cripta y en el conocimiento hacer recobrar \u201cvida\u201d a Sinforosa Rolon y Rubio, incluso los guiados tomaron imagen del mism\u00edsimo templo con sus luces encendidas.<\/p>\n<p style=\"font-weight: 400;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-27897\" src=\"https:\/\/radiobitacora.com.ar\/web\/wp-content\/uploads\/2025\/11\/Noche-de-los-Museos-en-Goya-14.jpg\" alt=\"\" width=\"1600\" height=\"1066\" srcset=\"https:\/\/radiobitacora.com.ar\/web\/wp-content\/uploads\/2025\/11\/Noche-de-los-Museos-en-Goya-14.jpg 1600w, https:\/\/radiobitacora.com.ar\/web\/wp-content\/uploads\/2025\/11\/Noche-de-los-Museos-en-Goya-14-630x420.jpg 630w, https:\/\/radiobitacora.com.ar\/web\/wp-content\/uploads\/2025\/11\/Noche-de-los-Museos-en-Goya-14-696x464.jpg 696w, https:\/\/radiobitacora.com.ar\/web\/wp-content\/uploads\/2025\/11\/Noche-de-los-Museos-en-Goya-14-1068x712.jpg 1068w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/p>\n<p style=\"font-weight: 400;\">La noche avanzaba y el \u201cmicro\u201d con sus pasajeros continuaba poniendo destino a cada espacio seleccionado para el recorrido que incluy\u00f3 la Prefectura Goya, la Biblioteca Popular \u201cDomingo Faustino Sarmiento\u201d, algunos hicieron su paso por la casa museo del primer obispo de Goya Monse\u00f1or Alberto Devoto, el Teatro Municipal, donde los responsables de historiar el s\u00edmbolo cultural de mayor vigencia en el pa\u00eds, no se privaron de nada incluyendo la aparici\u00f3n de \u201cduendes\u201d; \u201cfantasmas\u201d no el de la \u00f3pera, sino el del Teatro Solari generando mayor inter\u00e9s en los visitantes, la gira continu\u00f3 hacia un espacio de excelencia en la calidad de muestra de arte Muda, donde los responsables del espacio art\u00edstico agradecieron la presencia dando detalles de la idea del lugar, del prop\u00f3sito de contar con un nuevo \u00e1mbito para la expresi\u00f3n art\u00edstica en la ciudad.<\/p>\n<p style=\"font-weight: 400;\">Algunos de los detalles de una excelente y brillante propuesta cultural, hist\u00f3rica y tur\u00edstica que puso en valor la riqueza de la ciudad afirmando el objetivo de ser un \u201cdestino tur\u00edstico\u201d<\/p>\n<p style=\"font-weight: 400;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-27898\" src=\"https:\/\/radiobitacora.com.ar\/web\/wp-content\/uploads\/2025\/11\/Noche-de-los-Museos-en-Goya-1.jpg\" alt=\"\" width=\"1600\" height=\"1066\" srcset=\"https:\/\/radiobitacora.com.ar\/web\/wp-content\/uploads\/2025\/11\/Noche-de-los-Museos-en-Goya-1.jpg 1600w, https:\/\/radiobitacora.com.ar\/web\/wp-content\/uploads\/2025\/11\/Noche-de-los-Museos-en-Goya-1-630x420.jpg 630w, https:\/\/radiobitacora.com.ar\/web\/wp-content\/uploads\/2025\/11\/Noche-de-los-Museos-en-Goya-1-696x464.jpg 696w, https:\/\/radiobitacora.com.ar\/web\/wp-content\/uploads\/2025\/11\/Noche-de-los-Museos-en-Goya-1-1068x712.jpg 1068w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-27899\" src=\"https:\/\/radiobitacora.com.ar\/web\/wp-content\/uploads\/2025\/11\/Noche-de-los-Museos-en-Goya-10.jpg\" alt=\"\" width=\"1600\" height=\"1066\" srcset=\"https:\/\/radiobitacora.com.ar\/web\/wp-content\/uploads\/2025\/11\/Noche-de-los-Museos-en-Goya-10.jpg 1600w, https:\/\/radiobitacora.com.ar\/web\/wp-content\/uploads\/2025\/11\/Noche-de-los-Museos-en-Goya-10-630x420.jpg 630w, https:\/\/radiobitacora.com.ar\/web\/wp-content\/uploads\/2025\/11\/Noche-de-los-Museos-en-Goya-10-696x464.jpg 696w, https:\/\/radiobitacora.com.ar\/web\/wp-content\/uploads\/2025\/11\/Noche-de-los-Museos-en-Goya-10-1068x712.jpg 1068w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/p>\n<p style=\"font-weight: 400;\">No se puede dejar de mencionar en el marco de la Noche de los Museos, en una fecha particular para los m\u00fasicos, el D\u00eda de la M\u00fasica, en honor a Santa Cecilia, en Casa de la Cultura, en el Patio de las Palmeras, \u201c Pa&#8217;i Juli\u00e1n Zini\u201d se prepar\u00f3 la convocatoria Acorde de Sonidos con la participaci\u00f3n de los Coros Infanto Juvenil, bajo la direcci\u00f3n de la Profesora Selva Vera; de los estudiantes de la carrera de Profesorado de M\u00fasica del ISG, el Polif\u00f3nico Municipal \u201cElidia Andino \u201cdirigido por su fundadora la profesora Elidia Andino, de manera solistas integrantes del Coro Infanto Juvenil interpretaron varias canciones y la Escuela de M\u00fasica \u201cAlcides Romero\u201d bajo la coordinaci\u00f3n de su Director Profesor Lisandro Mart\u00ednez, con la presentaci\u00f3n de sus integrantes en la interpretaci\u00f3n de los instrumentos musicales que aprenden su ejecuci\u00f3n en ese \u00a0espacio educativo musical, deleitando al gran n\u00famero de espectadores que se convoc\u00f3 en la hist\u00f3rica casona, sum\u00e1ndose aquellos que participaron del recorrido por los otros espacios de Goya.<\/p>\n<p style=\"font-weight: 400;\">Una noche inolvidable, de grandes experiencias, que sirvi\u00f3 para una gran apertura a la historia, la cultura, la riqueza de nuestra identidad, convirtiendo a la propuesta en una interesante proyecci\u00f3n tur\u00edstica.<\/p>\n<p style=\"font-weight: 400;\">Como en un cuento cl\u00e1sico de la Literatura Infantil, a las 00: 00 horas, el colectivo que transportaba a los visitantes concluy\u00f3 con su recorrido, dejando a cada pasajero con la sensaci\u00f3n de haber compartido la vida con los personajes, personalidades que dieron la esencia al ser goyano\u2026con la promesa de volver a recorrer cada rinc\u00f3n de la ciudad y aguardar para una nueva propuesta de estas caracter\u00edsticas para ser \u201catrapados\u201d por el \u201cencanto\u201d de Goya\u2026Hasta la pr\u00f3xima, chamigo\u2026.<\/p>\n<p style=\"font-weight: 400;\">Direcci\u00f3n de Prensa-Municipalidad de Goya<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cLA NOCHE DE LOS MUSEOS\u201d Un itinerario propuesto para recorrer los lugares ic\u00f3nicos y emblem\u00e1ticos de la ciudad de Goya, rescatando gracias al aporte de los gu\u00edas urbanos y de sitio la riqueza patrimonial de la ciudad. La iniciativa el s\u00e1bado dio inicio pasadas las 18 y 30 horas con la partida del \u201ccolectivo\u201d dispuesto [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":27898,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-27894","post","type-post","status-publish","format-standard","has-post-thumbnail","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/posts\/27894","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/comments?post=27894"}],"version-history":[{"count":0,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/posts\/27894\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/media\/27898"}],"wp:attachment":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/media?parent=27894"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/categories?post=27894"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/tags?post=27894"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}