{"id":28906,"date":"2026-01-05T18:11:52","date_gmt":"2026-01-05T21:11:52","guid":{"rendered":"https:\/\/radiobitacora.com.ar\/web\/?p=28906"},"modified":"2026-01-05T18:12:00","modified_gmt":"2026-01-05T21:12:00","slug":"ministro-de-desarrollo-social-jose-irigoyen-visito-goya","status":"publish","type":"post","link":"https:\/\/radiobitacora.com.ar\/web\/2026\/01\/05\/ministro-de-desarrollo-social-jose-irigoyen-visito-goya\/","title":{"rendered":"MINISTRO DE DESARROLLO SOCIAL, JOS\u00c9 IRIGOYEN, VISIT\u00d3 GOYA"},"content":{"rendered":"<p style=\"font-weight: 400;\">El Ministro de Desarrollo Social de la Provincia de Corrientes, Dr. Jos\u00e9 Irigoyen recorri\u00f3 este domingo la delegaci\u00f3n del Ministerio de Desarrollo Social de la localidad de Goya.<\/p>\n<p style=\"font-weight: 400;\">Esta presencia en terreno tuvo como objetivo central, tener un conocimiento cabal de las actividades que realiza la sede en la segunda ciudad de la Provincia y poder trazar una hoja de ruta, de acuerdo a los preceptos que estableci\u00f3 el Gobernador Juan Pablo Vald\u00e9s<\/p>\n<p style=\"font-weight: 400;\">El ministro de Desarrollo Social, Dr. Jos\u00e9 Miguel Irigoyen se hizo presente junto a su equipo en las localidades afectadas por las \u00faltimas precipitaciones y posteriormente visit\u00f3 otros departamentos para relevar la situaci\u00f3n de las dependencias de Desarrollo Social.<\/p>\n<p style=\"font-weight: 400;\">Es as\u00ed que el ministro se reuni\u00f3 con el ingeniero Juan de la Cruz M\u00e1rquez, delegado regional de esta Cartera.<\/p>\n<p style=\"font-weight: 400;\">\u201cEs el segundo contacto en forma personal que tenemos con el ministro a partir de su inicio en esta cartera y, como est\u00e1 arrancando, nos estamos acomodando de a poco y por eso se retras\u00f3 la visita a nuestra delegaci\u00f3n\u201d dijo.<\/p>\n<p style=\"font-weight: 400;\">Seg\u00fan M\u00e1rquez, Irigoyen fue informado acerca del manejo del \u00e1rea de influencia de la delegaci\u00f3n local, qu\u00e9 \u00e1reas abarca, a qu\u00e9 cantidad de beneficiarios da alcance, qu\u00e9 recursos tiene. \u201cVino a ponerse a disposici\u00f3n y nos pusimos al d\u00eda cada uno de nosotros en cada uno de los aspectos en que nosotros trabajamos en la zona\u201d indic\u00f3 este lunes 05 ante micr\u00f3fonos de RADIO CIUDAD 88.3.<\/p>\n<p style=\"font-weight: 400;\">OPERATIVOS AL CAMPO<\/p>\n<p style=\"font-weight: 400;\">El ministerio de Desarrollo Social de la provincia de Corrientes, a trav\u00e9s de operativos al campo con los municipios, asiste a poblaciones vulnerables, coordinando programas alimentarios para responder a necesidades b\u00e1sicas.<\/p>\n<p style=\"font-weight: 400;\">En este sentido, M\u00e1rquez explic\u00f3 que otras de las conversaciones que se dio este domingo entre sendos funcionarios es la continuidad de esta asistencia, dos veces por semana, acompa\u00f1ando con m\u00f3dulos de mercader\u00eda en operativos sanitarios armados por la Municipalidad de Goya.<\/p>\n<p style=\"font-weight: 400;\">\u201cLe explicamos al ministro que nuestro departamento es especial debido a la extensi\u00f3n y cantidad de poblaci\u00f3n que existe en la zona rural y lo que significa la cantidad de kil\u00f3metros que tenemos que recorrer para llegar a la poblaci\u00f3n m\u00e1s alejada\u201d.<\/p>\n<p style=\"font-weight: 400;\">Aclar\u00f3 que se le puntualiz\u00f3 atender el tema movilidad toda vez que el veh\u00edculo disponible no estar\u00eda siendo el indicado para acceder a estos lugares de dif\u00edcil acceso.<\/p>\n<p style=\"font-weight: 400;\">\u00a0APOYO A CLUBES E INSTITUCIONES<\/p>\n<p style=\"font-weight: 400;\">Como parte del compromiso sostenido del Gobierno para garantizar el derecho a la formaci\u00f3n deportiva, a trav\u00e9s de la articulaci\u00f3n de programas con clubes, M\u00e1rquez puso el foco en que desde su delegaci\u00f3n se asiste a m\u00e1s de 1.300 beneficiarios, 10 clubes e instituciones de ciudad y campo con copas de leche (25 merenderos).<\/p>\n<p style=\"font-weight: 400;\">Asimismo, con m\u00f3dulos alimentarios se asiste a entidades como: APIPIE, Fundaci\u00f3n San Lucas, Coordinaci\u00f3n de Discapacidad, Coordinaci\u00f3n de la Pastoral de Adicciones entre otras.<\/p>\n<p style=\"font-weight: 400;\">Respecto al territorio y a la construcci\u00f3n colectiva de pol\u00edticas p\u00fablicas integrales se atiende desde Yatait\u00ed Calle, San Isidro, Carolina, parte de Lavalle, Ifr\u00e1n.<\/p>\n<p style=\"font-weight: 400;\">Finalmente, el funcionario local asever\u00f3 que seguir\u00e1n trabajando en la misma sinton\u00eda: \u201ccoincidimos en un mont\u00f3n de aspectos, viniendo de una intendencia (Irigoyen) conoce un mont\u00f3n de aspectos y realidades de una poblaci\u00f3n y sobre todo la situaci\u00f3n del sur de Corrientes\u201d cerr\u00f3.<\/p>\n<p style=\"font-weight: 400;\">Direcci\u00f3n de Prensa-Municipalidad de Goya<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Ministro de Desarrollo Social de la Provincia de Corrientes, Dr. Jos\u00e9 Irigoyen recorri\u00f3 este domingo la delegaci\u00f3n del Ministerio de Desarrollo Social de la localidad de Goya. Esta presencia en terreno tuvo como objetivo central, tener un conocimiento cabal de las actividades que realiza la sede en la segunda ciudad de la Provincia y [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":28907,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56],"tags":[],"class_list":["post-28906","post","type-post","status-publish","format-standard","has-post-thumbnail","category-locales"],"_links":{"self":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/posts\/28906","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/comments?post=28906"}],"version-history":[{"count":0,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/posts\/28906\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/media\/28907"}],"wp:attachment":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/media?parent=28906"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/categories?post=28906"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/tags?post=28906"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}