{"id":30347,"date":"2026-02-20T08:28:04","date_gmt":"2026-02-20T11:28:04","guid":{"rendered":"https:\/\/radiobitacora.com.ar\/web\/?p=30347"},"modified":"2026-02-20T08:28:12","modified_gmt":"2026-02-20T11:28:12","slug":"mauricio-dayub-llegara-a-goya-con-su-aclamado-unipersonal-el-equilibrista","status":"publish","type":"post","link":"https:\/\/radiobitacora.com.ar\/web\/2026\/02\/20\/mauricio-dayub-llegara-a-goya-con-su-aclamado-unipersonal-el-equilibrista\/","title":{"rendered":"MAURICIO DAYUB LLEGAR\u00c1 A GOYA CON SU ACLAMADO UNIPERSONAL &#8220;EL EQUILIBRISTA&#8221;"},"content":{"rendered":"<p style=\"font-weight: 400;\"><strong><em>El reconocido actor argentino Mauricio Dayub se prepara para desembarcar en el Teatro Municipal de Goya el pr\u00f3ximo 22 de marzo con su multipremiado unipersonal &#8220;El Equilibrista&#8221;. \u201cEs un espect\u00e1culo que acerca, que nos representa a todos&#8230;\u201d, dijo sobre este viaje a las ra\u00edces, a los v\u00ednculos familiares y en b\u00fasqueda constante del equilibrio emocional.<\/em><\/strong><\/p>\n<p style=\"font-weight: 400;\">La obra, que han visto m\u00e1s de 450.000 espectadores a lo largo de ocho a\u00f1os, promete una noche inolvidable de reflexi\u00f3n y humor.<\/p>\n<p>Mauricio Dayub, reconocido con el premio Konex de Platino al mejor unipersonal de la d\u00e9cada, expres\u00f3 su entusiasmo por presentarse por primera vez en la ciudad de Goya: &#8220;Me va a dar un enorme placer, ser\u00e1 la primera vez que voy a Goya. No he estado nunca y me he propuesto este a\u00f1o llegar a ciudades donde no he podido estar&#8221;, dijo.<\/p>\n<p>El actor, que ha recorrido m\u00e1s de 72 ciudades en Argentina y cinco pa\u00edses con este espect\u00e1culo, se siente identificado con el esp\u00edritu viajero de su padre y de esta manera lo vincula con su profesi\u00f3n: &#8220;Mi pap\u00e1 era viajante y recorr\u00eda peque\u00f1os pueblos. Lo acompa\u00f1\u00e9 en un momento cuando no sab\u00eda encarar esta profesi\u00f3n y he descubierto que hago lo que hac\u00eda mi pap\u00e1, haciendo kil\u00f3metros con el auto para reencontrarme con la gente. En lugar de ofrecer una mercader\u00eda, ofrezco mi propia vida e historias con un equipo de gente que me acompa\u00f1a&#8221;.<\/p>\n<p>El espect\u00e1culo, que ha cosechado elogios de la cr\u00edtica y el cari\u00f1o del p\u00fablico, presenta a Dayub interpretando ocho personajes, cada uno con su propia voz y personalidad. Algunos de ellos se materializan con vestuario y peluca, mientras que otros son apenas sugeridos, dejando que la imaginaci\u00f3n del espectador complete la escena.<\/p>\n<p style=\"font-weight: 400;\">&#8220;Es muy lindo cuando los espectadores me elogian dici\u00e9ndome que no era unipersonal, sino que hab\u00eda muchos personajes en el escenario&#8230; Al sugerir, el espectador le va poniendo el nombre de sus propios familiares&#8221;, dijo el actor.<\/p>\n<p style=\"font-weight: 400;\">Dayub tambi\u00e9n comparti\u00f3 una an\u00e9cdota personal que revela el origen de la obra. &#8220;Cuento secretos de mi familia que mi abuela ocult\u00f3 durante muchos a\u00f1os y que, de casualidad, porque llov\u00eda en Yugoslavia donde fui a filmar una pel\u00edcula y me dieron dos d\u00edas libres, decid\u00ed ir al pueblo donde naci\u00f3 ella&#8230; De repente se produjo ese fen\u00f3meno extraordinario que es la esencia de &#8216;El Equilibrista&#8217;: la vida simple y humilde de mi madre y abuelos&#8221;.<\/p>\n<p style=\"font-weight: 400;\">El actor tambi\u00e9n reflexion\u00f3 sobre el impacto que genera &#8220;El Equilibrista&#8221; en el p\u00fablico y expres\u00f3: &#8220;Es un espect\u00e1culo que no es de los que te deja afuera y para admirar solamente, sino que es un espect\u00e1culo que acerca, que nos representa a todos&#8230; Nunca imagin\u00e9 que ser actor me iba a poner en este lugar hermoso de que lo que hago vaya m\u00e1s all\u00e1 del arte, sino que mejore mi propia vida, hay algo humano que me gusta mucho&#8221;.<\/p>\n<p style=\"font-weight: 400;\">Dayub record\u00f3 los consejos de Carlos Rottemberg, quien lo impuls\u00f3 a ofrecer una garant\u00eda de satisfacci\u00f3n al p\u00fablico. &#8220;Me dijo que promocione como teatro con garant\u00eda, porque no fallaba. Lo hice y lo complet\u00e9 diciendo que, si no te llega a gustar, te espero en el hall y te devuelvo el dinero de la entrada, y es por eso que tuve que estar en el hall de todos los teatros&#8221;.<\/p>\n<p><span style=\"font-weight: 400;\">En estos d\u00edas, Dayub retom\u00f3 las funciones de &#8220;El Equilibrista&#8221; en la calle Corrientes, en el Teatro Nacional, y coment\u00f3 sobre esto: &#8220;Retomamos en la calle Corrientes en el Teatro Nacional y fue tan hermoso, y digo qu\u00e9 fuerza tiene este espect\u00e1culo, cu\u00e1ntas cosas logra\u2026&#8221;, destac\u00f3 el actor.<\/span><\/p>\n<p>&#8220;El Equilibrista&#8221;, escrita en colaboraci\u00f3n con Patricio Abadi y Mariano Saba, es mucho m\u00e1s que una obra de teatro; es un viaje a las ra\u00edces, una exploraci\u00f3n de los v\u00ednculos familiares y una b\u00fasqueda constante del equilibrio emocional. En palabras del propio Dayub: &#8220;Mi abuelo tocaba el acorde\u00f3n junto a una caja que dec\u00eda &#8216;Fr\u00e1gil&#8217;. Una caja similar a la que mi padre usaba para guardar las obras de arte que remataba&#8230; Ahora entiendo por qu\u00e9&#8221;.<\/p>\n<p>Direcci\u00f3n de Prensa &#8211; Municipalidad de Goya<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El reconocido actor argentino Mauricio Dayub se prepara para desembarcar en el Teatro Municipal de Goya el pr\u00f3ximo 22 de marzo con su multipremiado unipersonal &#8220;El Equilibrista&#8221;. \u201cEs un espect\u00e1culo que acerca, que nos representa a todos&#8230;\u201d, dijo sobre este viaje a las ra\u00edces, a los v\u00ednculos familiares y en b\u00fasqueda constante del equilibrio emocional. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":30348,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56],"tags":[],"class_list":["post-30347","post","type-post","status-publish","format-standard","has-post-thumbnail","category-locales"],"_links":{"self":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/posts\/30347","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/comments?post=30347"}],"version-history":[{"count":0,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/posts\/30347\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/media\/30348"}],"wp:attachment":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/media?parent=30347"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/categories?post=30347"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/tags?post=30347"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}