{"id":30371,"date":"2026-02-20T18:28:50","date_gmt":"2026-02-20T21:28:50","guid":{"rendered":"https:\/\/radiobitacora.com.ar\/web\/?p=30371"},"modified":"2026-02-20T18:31:14","modified_gmt":"2026-02-20T21:31:14","slug":"fundacion-agora-y-editorial-arandu-presentaron-una-nueva-revista-digital-y-fortalecen-su-propuesta-de-formacion-docente","status":"publish","type":"post","link":"https:\/\/radiobitacora.com.ar\/web\/2026\/02\/20\/fundacion-agora-y-editorial-arandu-presentaron-una-nueva-revista-digital-y-fortalecen-su-propuesta-de-formacion-docente\/","title":{"rendered":"FUNDACI\u00d3N \u00c1GORA Y EDITORIAL ARAND\u00da PRESENTARON UNA NUEVA REVISTA DIGITAL Y FORTALECEN SU PROPUESTA DE FORMACI\u00d3N DOCENTE"},"content":{"rendered":"<p data-start=\"123\" data-end=\"423\">En la ma\u00f1ana del 19 de febrero, en los estudios de Radio Bit\u00e1cora de Goya, integrantes de la Fundaci\u00f3n \u00c1gora y de la Editorial Arand\u00fa brindaron detalles sobre el lanzamiento de una nueva revista digital y la continuidad de las propuestas acad\u00e9micas destinadas a docentes y profesionales de la regi\u00f3n.<\/p>\n<p data-start=\"425\" data-end=\"819\">Participaron de la entrevista la licenciada Laura Vicent\u00edn, la responsable de la Fundaci\u00f3n \u00c1gora, Liliana Lesteime, y el abogado Emanuel Blanco, asesor legal de la instituci\u00f3n, concejal electo y uno de los responsables de la Editorial Arand\u00fa. Durante el di\u00e1logo, destacaron la importancia de la formaci\u00f3n continua como herramienta clave para el desarrollo profesional y el crecimiento personal.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-30375 alignleft\" src=\"https:\/\/radiobitacora.com.ar\/web\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-19-at-10.10.04-AM.jpeg\" alt=\"\" width=\"312\" height=\"234\" srcset=\"https:\/\/radiobitacora.com.ar\/web\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-19-at-10.10.04-AM.jpeg 1600w, https:\/\/radiobitacora.com.ar\/web\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-19-at-10.10.04-AM-560x420.jpeg 560w, https:\/\/radiobitacora.com.ar\/web\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-19-at-10.10.04-AM-80x60.jpeg 80w, https:\/\/radiobitacora.com.ar\/web\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-19-at-10.10.04-AM-696x522.jpeg 696w, https:\/\/radiobitacora.com.ar\/web\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-19-at-10.10.04-AM-1068x801.jpeg 1068w, https:\/\/radiobitacora.com.ar\/web\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-19-at-10.10.04-AM-265x198.jpeg 265w\" sizes=\"auto, (max-width: 312px) 100vw, 312px\" \/><\/p>\n<p data-start=\"821\" data-end=\"860\">REVISTA DIGITAL CON M\u00c1S DE 40 AUTORES<\/p>\n<p data-start=\"862\" data-end=\"1091\">Uno de los ejes centrales fue la presentaci\u00f3n oficial de la revista digital de la Editorial Arand\u00fa, cuyo lanzamiento se realiz\u00f3 ese mismo d\u00eda a las 20 horas en la sede de la Fundaci\u00f3n \u00c1gora, ubicada en calle Ver\u00f3n de Astrada 232.<\/p>\n<p data-start=\"1093\" data-end=\"1403\">Blanco explic\u00f3 que la editorial naci\u00f3 originalmente como un espacio destinado a transformar tesis doctorales, trabajos de maestr\u00eda y producciones acad\u00e9micas en libros. Con el tiempo, ampli\u00f3 su horizonte incorporando obras literarias, textos de opini\u00f3n y producciones culturales de autores locales y regionales.<\/p>\n<p data-start=\"1405\" data-end=\"1692\">Tras el fallecimiento de Daniel Lesteime, impulsor del proyecto y referente de la educaci\u00f3n en la ciudad, el equipo decidi\u00f3 reorganizar y relanzar la iniciativa. En ese proceso surgi\u00f3 la idea de crear una revista digital como plataforma abierta para escritores, docentes y profesionales.<\/p>\n<p data-start=\"1694\" data-end=\"2047\">Seg\u00fan detall\u00f3 Blanco, al momento del lanzamiento ya contaban con m\u00e1s de 40 personas escribiendo para la revista, muchas de las cuales enviaron varios art\u00edculos para su publicaci\u00f3n a lo largo del a\u00f1o. La revista es de acceso libre y gratuito a trav\u00e9s del sitio revistaarandu.com y busca convertirse en un espacio plural de expresi\u00f3n acad\u00e9mica y cultural.<\/p>\n<p data-start=\"2049\" data-end=\"2317\">Adem\u00e1s, la editorial firm\u00f3 un convenio con Ediciones de la Paz, lo que permitir\u00e1 acompa\u00f1ar a escritores goyanos en los procesos de edici\u00f3n, maquetaci\u00f3n, registro y publicaci\u00f3n de libros, facilitando el acceso a herramientas profesionales para la difusi\u00f3n de sus obras.<\/p>\n<p data-start=\"2049\" data-end=\"2317\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-30374 alignleft\" src=\"https:\/\/radiobitacora.com.ar\/web\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-19-at-10.10.05-AM.jpeg\" alt=\"\" width=\"288\" height=\"216\" srcset=\"https:\/\/radiobitacora.com.ar\/web\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-19-at-10.10.05-AM.jpeg 1600w, https:\/\/radiobitacora.com.ar\/web\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-19-at-10.10.05-AM-560x420.jpeg 560w, https:\/\/radiobitacora.com.ar\/web\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-19-at-10.10.05-AM-80x60.jpeg 80w, https:\/\/radiobitacora.com.ar\/web\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-19-at-10.10.05-AM-696x522.jpeg 696w, https:\/\/radiobitacora.com.ar\/web\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-19-at-10.10.05-AM-1068x801.jpeg 1068w, https:\/\/radiobitacora.com.ar\/web\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-19-at-10.10.05-AM-265x198.jpeg 265w\" sizes=\"auto, (max-width: 288px) 100vw, 288px\" \/><\/p>\n<p data-start=\"2319\" data-end=\"2358\">OFERTA ACAD\u00c9MICA Y FORMACI\u00d3N CONTINUA<\/p>\n<p data-start=\"2360\" data-end=\"2660\">Por su parte, la licenciada Laura Vicent\u00edn detall\u00f3 la propuesta acad\u00e9mica que la Fundaci\u00f3n \u00c1gora desarrolla en convenio con la Universidad del Chaco Austral. Estas carreras est\u00e1n orientadas a docentes en ejercicio y a profesionales que cuenten con t\u00edtulo de grado de al menos cuatro a\u00f1os de duraci\u00f3n.<\/p>\n<p data-start=\"2662\" data-end=\"2966\">Actualmente se dictan licenciaturas en Educaci\u00f3n Inicial, en Gesti\u00f3n Educativa y en Educaci\u00f3n. Cada una tiene una duraci\u00f3n de dos a\u00f1os y otorga un puntaje significativo en el escalaf\u00f3n docente, lo que impacta directamente en las oportunidades laborales y en la posibilidad de concursar cargos directivos.<\/p>\n<p data-start=\"2968\" data-end=\"3301\">Vicent\u00edn explic\u00f3 que estas licenciaturas no solo mejoran el puntaje, sino que fortalecen la formaci\u00f3n en \u00e1reas como did\u00e1ctica, pedagog\u00eda, pol\u00edtica educativa y liderazgo institucional. En el caso de Gesti\u00f3n Educativa, por ejemplo, la propuesta resulta especialmente valiosa para quienes aspiran a desempe\u00f1arse en cargos de conducci\u00f3n.<\/p>\n<p data-start=\"3303\" data-end=\"3613\">La modalidad es a distancia, pero con acompa\u00f1amiento local. La Fundaci\u00f3n ofrece apoyo administrativo y pedag\u00f3gico, seguimiento de cursado y asesoramiento para la presentaci\u00f3n de trabajos, teniendo en cuenta que la mayor\u00eda de los estudiantes son docentes en actividad que deben compatibilizar estudio y trabajo.<\/p>\n<p data-start=\"3615\" data-end=\"3960\">En cuanto a los costos, informaron que la cuota mensual es de 40 mil pesos, con matr\u00edcula inicial y un arancel que puede actualizarse semestralmente seg\u00fan lo determine la universidad. Desde la instituci\u00f3n destacaron que se trata de una propuesta accesible en relaci\u00f3n con la formaci\u00f3n que brinda y el impacto que tiene en la carrera profesional.<\/p>\n<p data-start=\"3962\" data-end=\"4009\">UNA APUESTA A LA EDUCACI\u00d3N Y LA CULTURA LOCAL<\/p>\n<p data-start=\"4011\" data-end=\"4324\">Durante la entrevista se puso en valor la visi\u00f3n de Daniel Lesteime, recordado como un impulsor de espacios donde convergen academia, cultura y educaci\u00f3n. Sus colegas subrayaron que la continuidad y expansi\u00f3n de los proyectos de la Fundaci\u00f3n \u00c1gora y la Editorial Arand\u00fa representan la consolidaci\u00f3n de ese legado.<\/p>\n<p data-start=\"4326\" data-end=\"4809\" data-is-last-node=\"\" data-is-only-node=\"\">La presentaci\u00f3n de la revista digital y el fortalecimiento de la oferta acad\u00e9mica reflejan una apuesta concreta por la formaci\u00f3n continua y por la generaci\u00f3n de espacios para la producci\u00f3n intelectual en Goya y la regi\u00f3n. Con herramientas digitales, acompa\u00f1amiento institucional y una red de profesionales comprometidos, la Fundaci\u00f3n \u00c1gora busca seguir ampliando oportunidades para docentes, escritores y estudiantes que deseen crecer y proyectarse en el \u00e1mbito educativo y cultural.<\/p>\n<div class=\"td-post-content tagdiv-type\">\n<p data-start=\"4212\" data-end=\"4384\" data-is-last-node=\"\" data-is-only-node=\"\"><em><strong>Fuentes<\/strong>\u00a0<\/em>: Multiplataformas Bitacora<\/p>\n<\/div>\n<footer>\n<div class=\"td-post-source-tags\"><\/div>\n<div class=\"td-post-sharing-bottom\"><\/div>\n<\/footer>\n","protected":false},"excerpt":{"rendered":"<p>En la ma\u00f1ana del 19 de febrero, en los estudios de Radio Bit\u00e1cora de Goya, integrantes de la Fundaci\u00f3n \u00c1gora y de la Editorial Arand\u00fa brindaron detalles sobre el lanzamiento de una nueva revista digital y la continuidad de las propuestas acad\u00e9micas destinadas a docentes y profesionales de la regi\u00f3n. Participaron de la entrevista la [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":30372,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[74],"tags":[],"class_list":["post-30371","post","type-post","status-publish","format-standard","has-post-thumbnail","category-bitacora-tv"],"_links":{"self":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/posts\/30371","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/comments?post=30371"}],"version-history":[{"count":0,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/posts\/30371\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/media\/30372"}],"wp:attachment":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/media?parent=30371"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/categories?post=30371"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/tags?post=30371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}