{"id":30459,"date":"2026-02-23T10:39:50","date_gmt":"2026-02-23T13:39:50","guid":{"rendered":"https:\/\/radiobitacora.com.ar\/web\/?p=30459"},"modified":"2026-02-23T10:41:03","modified_gmt":"2026-02-23T13:41:03","slug":"la-abogada-argentina-detenida-por-racismo-en-brasil-denuncio-que-la-amenazan-por-redes-vas-a-morir","status":"publish","type":"post","link":"https:\/\/radiobitacora.com.ar\/web\/2026\/02\/23\/la-abogada-argentina-detenida-por-racismo-en-brasil-denuncio-que-la-amenazan-por-redes-vas-a-morir\/","title":{"rendered":"LA ABOGADA ARGENTINA DETENIDA POR RACISMO EN BRASIL DENUNCI\u00d3 QUE LA AMENAZAN POR REDES: \u201cVAS A MORIR\u201d"},"content":{"rendered":"<h2 class=\"article__dropline font__body\">Agostina P\u00e1ez enfrenta una causa judicial en R\u00edo de Janeiro y expuso en Instagram los mensajes intimidatorios que recibe desde que fue denunciada.<\/h2>\n<p class=\"paragraph font__body-regular\">La\u00a0<a title=\"https:\/\/tn.com.ar\/policiales\/2026\/02\/06\/la-abogada-argentina-acusada-de-hacer-gestos-racistas-quedo-detenida-en-una-comisaria-de-brasil\/\" href=\"https:\/\/tn.com.ar\/policiales\/2026\/02\/06\/la-abogada-argentina-acusada-de-hacer-gestos-racistas-quedo-detenida-en-una-comisaria-de-brasil\/\" target=\"_blank\" rel=\"noopener noreferrer\"><b>abogada argentina Agostina P\u00e1ez<\/b><\/a>\u00a0denunci\u00f3 que\u00a0<b>recibe amenazas de muerte<\/b> e insultos violentos a trav\u00e9s de sus redes sociales.<\/p>\n<div class=\"AV6543bedcd858799fe90b5c47\">\n<div id=\"aniBox\">\n<div id=\"aniplayer_AV6543bedcd858799fe90b5c47-1771853812322\">\n<div id=\"aniplayer_AV6543bedcd858799fe90b5c47-1771853812322gui\">\n<div id=\"av-container\" class=\" av-desktop hide-controls\">\n<div id=\"av-inner\">\n<div id=\"slot\">\n<div id=\"imgpreloader\">\n<div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p class=\"paragraph font__body-regular\">P\u00e1ez, que est\u00e1 retenida en R\u00edo de Janeiro desde mediados de enero por una causa de<b>\u00a0racismo\u00a0<\/b>contra un mozo, us\u00f3 su cuenta de Instagram para mostrar el\u00a0<b>hostigamiento que sufre\u00a0<\/b>mientras avanza la investigaci\u00f3n judicial.<\/p>\n<p class=\"paragraph font__body-regular\">En una serie de historias, P\u00e1ez comparti\u00f3 capturas de pantalla con mensajes cargados de insultos, amenazas sexuales y de muerte, la mayor\u00eda en portugu\u00e9s, pero tambi\u00e9n de usuarios argentinos.<\/p>\n<p class=\"paragraph font__body-regular\"><b>\u201cCuidado en caminar sola\u201d, \u201cracista no vas a tener paz\u201d, \u201cespero te mates, puta racista\u201d y \u201cvas a morir\u201d<\/b>\u00a0son solo algunas de las frases que le enviaron. Muchos de estos mensajes incluyen emojis de calaveras y agravios dirigidos a ella y a su familia.<\/p>\n<figure class=\"\" data-testid=\"figure-testid\">\n<div class=\"aspect_ratio__container\"><picture class=\"responsive-image\"><source srcset=\"https:\/\/tn.com.ar\/resizer\/v2\/algunos-de-los-mensajes-que-recibio-la-abogada-detenida-por-racismo-en-brasil-foto-instagram-agostinapaez-D745PCW5JJEPLFXYYAC4OZDRZI.png?auth=caf4bac389417b4df81c1ffd1d04f5bb2bd86c2f8c31bc896f9ed89b9efc137a&amp;width=767\" type=\"image\/jpg\" media=\"(max-width: 728px)\" \/><source srcset=\"https:\/\/tn.com.ar\/resizer\/v2\/algunos-de-los-mensajes-que-recibio-la-abogada-detenida-por-racismo-en-brasil-foto-instagram-agostinapaez-D745PCW5JJEPLFXYYAC4OZDRZI.png?auth=caf4bac389417b4df81c1ffd1d04f5bb2bd86c2f8c31bc896f9ed89b9efc137a&amp;width=1023\" type=\"image\/jpg\" media=\"(max-width: 1023px)\" \/><source srcset=\"https:\/\/tn.com.ar\/resizer\/v2\/algunos-de-los-mensajes-que-recibio-la-abogada-detenida-por-racismo-en-brasil-foto-instagram-agostinapaez-D745PCW5JJEPLFXYYAC4OZDRZI.png?auth=caf4bac389417b4df81c1ffd1d04f5bb2bd86c2f8c31bc896f9ed89b9efc137a&amp;width=1440\" type=\"image\/jpg\" \/><img loading=\"lazy\" decoding=\"async\" class=\"image content-image image_placeholder\" src=\"https:\/\/tn.com.ar\/resizer\/v2\/algunos-de-los-mensajes-que-recibio-la-abogada-detenida-por-racismo-en-brasil-foto-instagram-agostinapaez-D745PCW5JJEPLFXYYAC4OZDRZI.png?auth=caf4bac389417b4df81c1ffd1d04f5bb2bd86c2f8c31bc896f9ed89b9efc137a&amp;width=767\" alt=\"Algunos de los mensajes que recibi\u00f3 la abogada detenida por racismo en Brasil. (Foto: instagram @agostinapaez)\" width=\"767\" height=\"430\" data-testid=\"loading-testid\" \/><\/picture><\/div><figcaption class=\"caption_image\" data-testid=\"figcaption-testid\">\n<div class=\"image_caption \">Algunos de los mensajes que recibi\u00f3 la abogada detenida por racismo en Brasil. (Foto: instagram @agostinapaez)<\/div>\n<\/figcaption><\/figure>\n<p class=\"paragraph font__body-regular\">Uno de los comentarios m\u00e1s duros que recibi\u00f3 fue: \u201c<b>Llev\u00e1 cuidado cuando est\u00e9s en la calle<\/b>. La paliza que te vamos a dar. Sudaca de mierda, muerta de hambre. Dos pu\u00f1aladas y una zorra menos. Que a una perra la acuestan por 200 euros. Ya veremos\u00a0<b>la alegr\u00eda que les va a dar a tus padres llevarte flores<\/b>\u201d.<\/p>\n<p class=\"paragraph font__body-regular\">Otro usuario le escribi\u00f3: \u201c<b>Ojal\u00e1 te violen, pinche pobrentina<\/b>.<b>\u00a0<\/b>Eres una basura. Argensimia\u201d. Incluso, algunos mensajes piden \u201cjusticia por mano propia\u201d y critican al sistema judicial brasile\u00f1o: \u201cEl racismo se combate a las pi\u00f1as, no sirve esperar justicia de un poder judicial blanco y elitista\u201d.<\/p>\n<figure class=\"\" data-testid=\"figure-testid\">\n<div class=\"aspect_ratio__container\"><picture class=\"responsive-image\"><source srcset=\"https:\/\/tn.com.ar\/resizer\/v2\/los-mensajes-a-la-abogada-denunciada-por-racismo-foto-instagram-agostinapaez-HPANFMLXWFGK7PPUECDHPNZL3I.png?auth=9fab5033dfa472e5b4dd3a9fbdee3a1f04163bf5cf696303c3567bf87977921d&amp;width=767\" type=\"image\/jpg\" media=\"(max-width: 728px)\" \/><source srcset=\"https:\/\/tn.com.ar\/resizer\/v2\/los-mensajes-a-la-abogada-denunciada-por-racismo-foto-instagram-agostinapaez-HPANFMLXWFGK7PPUECDHPNZL3I.png?auth=9fab5033dfa472e5b4dd3a9fbdee3a1f04163bf5cf696303c3567bf87977921d&amp;width=1023\" type=\"image\/jpg\" media=\"(max-width: 1023px)\" \/><source srcset=\"https:\/\/tn.com.ar\/resizer\/v2\/los-mensajes-a-la-abogada-denunciada-por-racismo-foto-instagram-agostinapaez-HPANFMLXWFGK7PPUECDHPNZL3I.png?auth=9fab5033dfa472e5b4dd3a9fbdee3a1f04163bf5cf696303c3567bf87977921d&amp;width=1440\" type=\"image\/jpg\" \/><img loading=\"lazy\" decoding=\"async\" class=\"image content-image image_placeholder\" src=\"https:\/\/tn.com.ar\/resizer\/v2\/los-mensajes-a-la-abogada-denunciada-por-racismo-foto-instagram-agostinapaez-HPANFMLXWFGK7PPUECDHPNZL3I.png?auth=9fab5033dfa472e5b4dd3a9fbdee3a1f04163bf5cf696303c3567bf87977921d&amp;width=767\" alt=\"Los mensajes a la abogada denunciada por racismo. (Foto: Instagram @agostinapaez)\" width=\"767\" height=\"430\" data-testid=\"loading-testid\" \/><\/picture><\/div><figcaption class=\"caption_image\" data-testid=\"figcaption-testid\">\n<div class=\"image_caption \">Los mensajes a la abogada denunciada por racismo. (Foto: Instagram @agostinapaez)<\/div>\n<\/figcaption><\/figure>\n<p class=\"paragraph font__body-regular\">Entre los mensajes m\u00e1s violentos, P\u00e1ez mostr\u00f3 uno que dec\u00eda: \u201c\u00bfEst\u00e1s lista para lamerle el culo a un mono? Llora m\u00e1s. Ten miedo. Si te quedas en la c\u00e1rcel de Brasil, vas a convertirte en una putita. Ahora baila como un mono. T\u00fa eres el ma\u00edz. Las monas te van a comer viva\u201d, acompa\u00f1ado por un video con la leyenda: \u201cNunca subestimes a una banda de monos\u201d.<\/p>\n<h2 class=\"font--primary font__display\">La abogada respondi\u00f3 a nuevas acusaciones y apunt\u00f3 contra una exmodelo<\/h2>\n<p class=\"paragraph font__body-regular\">En medio de la ola de mensajes, P\u00e1ez tambi\u00e9n sali\u00f3 al cruce de una usuaria que la acus\u00f3 de acoso escolar. \u201cNunca fui su compa\u00f1era, nunca me la cruc\u00e9, nunca fue testigo de su bullying\u201d, asegur\u00f3 la abogada santiague\u00f1a.<\/p>\n<figure class=\"\" data-testid=\"figure-testid\">\n<div class=\"aspect_ratio__container\"><picture class=\"responsive-image\"><source srcset=\"https:\/\/tn.com.ar\/resizer\/v2\/la-argentina-le-respondio-a-una-joven-que-dijo-ser-su-excompanera-foto-instagram-agostinapaez-HILTZ6SVDNHFBECDPMTK4WV2XQ.png?auth=32a691feb2247fde0baece87f17cb263b05e9e4608e80bb5b5cf72edadd30fc9&amp;width=767\" type=\"image\/jpg\" media=\"(max-width: 728px)\" \/><source srcset=\"https:\/\/tn.com.ar\/resizer\/v2\/la-argentina-le-respondio-a-una-joven-que-dijo-ser-su-excompanera-foto-instagram-agostinapaez-HILTZ6SVDNHFBECDPMTK4WV2XQ.png?auth=32a691feb2247fde0baece87f17cb263b05e9e4608e80bb5b5cf72edadd30fc9&amp;width=1023\" type=\"image\/jpg\" media=\"(max-width: 1023px)\" \/><source srcset=\"https:\/\/tn.com.ar\/resizer\/v2\/la-argentina-le-respondio-a-una-joven-que-dijo-ser-su-excompanera-foto-instagram-agostinapaez-HILTZ6SVDNHFBECDPMTK4WV2XQ.png?auth=32a691feb2247fde0baece87f17cb263b05e9e4608e80bb5b5cf72edadd30fc9&amp;width=1440\" type=\"image\/jpg\" \/><img loading=\"lazy\" decoding=\"async\" class=\"image content-image image_placeholder\" src=\"https:\/\/tn.com.ar\/resizer\/v2\/la-argentina-le-respondio-a-una-joven-que-dijo-ser-su-excompanera-foto-instagram-agostinapaez-HILTZ6SVDNHFBECDPMTK4WV2XQ.png?auth=32a691feb2247fde0baece87f17cb263b05e9e4608e80bb5b5cf72edadd30fc9&amp;width=767\" alt=\"La argentina le respondi\u00f3 a una joven que dijo ser su excompa\u00f1era. (Foto: Instagram @agostinapaez)\" width=\"767\" height=\"1528\" data-testid=\"loading-testid\" \/><\/picture><\/div><figcaption class=\"caption_image\" data-testid=\"figcaption-testid\">\n<div class=\"image_caption \">La argentina le respondi\u00f3 a una joven que dijo ser su excompa\u00f1era. (Foto: Instagram @agostinapaez)<\/div>\n<\/figcaption><\/figure>\n<p class=\"paragraph font__body-regular\">Adem\u00e1s, le dedic\u00f3 un mensaje a la exmodelo brasile\u00f1a Anam\u00e1 Ferreira, quien opin\u00f3 p\u00fablicamente sobre el caso. P\u00e1ez sostuvo que las afirmaciones de Ferreira \u201cno son ciertas\u201d y cont\u00f3:\u00a0<b>\u201cYo le mand\u00e9 un mensajito con todo el respeto y me bloque\u00f3\u201d<\/b>.<\/p>\n<p class=\"paragraph font__body-regular\">Mientras tanto,<b>\u00a0la abogada argentina no puede salir de Brasil y sigue bajo investigaci\u00f3n por \u201cinjuria racial\u201d<\/b>. Su defensa present\u00f3 un h\u00e1beas corpus de 50 p\u00e1ginas para cuestionar el proceso y reclamar garant\u00edas legales.<\/p>\n<p class=\"paragraph font__body-regular\">Seg\u00fan explic\u00f3 su padre, Mariano P\u00e1ez, el recurso detalla horarios, momentos del hecho y referencias a c\u00e1maras de seguridad que, seg\u00fan la defensa, no habr\u00edan sido incorporadas a la causa.<\/p>\n<p class=\"paragraph font__body-regular\">El planteo tambi\u00e9n cuestiona el uso de la imagen de P\u00e1ez en campa\u00f1as p\u00fablicas, al considerar que esa exposici\u00f3n ser\u00eda ilegal mientras no exista una condena firme.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Agostina P\u00e1ez enfrenta una causa judicial en R\u00edo de Janeiro y expuso en Instagram los mensajes intimidatorios que recibe desde que fue denunciada. La\u00a0abogada argentina Agostina P\u00e1ez\u00a0denunci\u00f3 que\u00a0recibe amenazas de muerte e insultos violentos a trav\u00e9s de sus redes sociales. P\u00e1ez, que est\u00e1 retenida en R\u00edo de Janeiro desde mediados de enero por una causa [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":30460,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[80],"tags":[],"class_list":["post-30459","post","type-post","status-publish","format-standard","has-post-thumbnail","category-internacionales"],"_links":{"self":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/posts\/30459","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/comments?post=30459"}],"version-history":[{"count":0,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/posts\/30459\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/media\/30460"}],"wp:attachment":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/media?parent=30459"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/categories?post=30459"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/tags?post=30459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}