{"id":30569,"date":"2026-02-25T09:50:05","date_gmt":"2026-02-25T12:50:05","guid":{"rendered":"https:\/\/radiobitacora.com.ar\/web\/?p=30569"},"modified":"2026-02-25T09:50:05","modified_gmt":"2026-02-25T12:50:05","slug":"la-policia-recupera-motocicleta-sustraida-y-la-aprehension-del-presunto-malhechor","status":"publish","type":"post","link":"https:\/\/radiobitacora.com.ar\/web\/2026\/02\/25\/la-policia-recupera-motocicleta-sustraida-y-la-aprehension-del-presunto-malhechor\/","title":{"rendered":"LA POLIC\u00cdA RECUPERA MOTOCICLETA SUSTRA\u00cdDA Y LA APREHENSI\u00d3N DEL PRESUNTO MALHECHOR"},"content":{"rendered":"<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">La Comisar\u00eda Primera de Goya informa que, en relaci\u00f3n al hurto de una motocicleta Zanella ZB, ocurrido el 30 de enero de 2026, en horas de la madrugada, cuando el rodado se encontraba estacionado sobre calle Bartolom\u00e9 Mitre al 1700, se llevaron adelante tareas investigativas tendientes al esclarecimiento del hecho.<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">Como resultado de una extensa investigaci\u00f3n realizada por personal policial, en la fecha se logr\u00f3 la recuperaci\u00f3n de la motocicleta sustra\u00edda, como as\u00ed tambi\u00e9n la aprehensi\u00f3n de una persona presuntamente vinculada al hecho, quien qued\u00f3 a disposici\u00f3n de la autoridad judicial competente.<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">El rodado recuperado ser\u00e1 restituido a su propietaria, previa cumplimentaci\u00f3n de las formalidades legales correspondientes.<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">Desde la Comisar\u00eda Primera de Goya se destaca el trabajo investigativo del personal policial, reafirmando el compromiso con la seguridad y la recuperaci\u00f3n de bienes sustra\u00eddos.<\/p>\n<p style=\"font-weight: 400;\">\n","protected":false},"excerpt":{"rendered":"<p>La Comisar\u00eda Primera de Goya informa que, en relaci\u00f3n al hurto de una motocicleta Zanella ZB, ocurrido el 30 de enero de 2026, en horas de la madrugada, cuando el rodado se encontraba estacionado sobre calle Bartolom\u00e9 Mitre al 1700, se llevaron adelante tareas investigativas tendientes al esclarecimiento del hecho. Como resultado de una extensa [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":30570,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[84],"tags":[],"class_list":["post-30569","post","type-post","status-publish","format-standard","has-post-thumbnail","category-policiales"],"_links":{"self":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/posts\/30569","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/comments?post=30569"}],"version-history":[{"count":0,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/posts\/30569\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/media\/30570"}],"wp:attachment":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/media?parent=30569"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/categories?post=30569"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/tags?post=30569"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}