{"id":30661,"date":"2026-02-26T09:05:59","date_gmt":"2026-02-26T12:05:59","guid":{"rendered":"https:\/\/radiobitacora.com.ar\/web\/?p=30661"},"modified":"2026-02-26T09:08:06","modified_gmt":"2026-02-26T12:08:06","slug":"espacios-para-las-danzas-nativas-y-el-teatro","status":"publish","type":"post","link":"https:\/\/radiobitacora.com.ar\/web\/2026\/02\/26\/espacios-para-las-danzas-nativas-y-el-teatro\/","title":{"rendered":"ESPACIOS PARA LAS DANZAS NATIVAS Y EL TEATRO"},"content":{"rendered":"<p style=\"font-weight: 400;\">La Municipalidad de Goya, a trav\u00e9s de Cultura, afianza los \u00e1mbitos de formaci\u00f3n en el aprendizaje del baile de las danzas nativas y en la adquisici\u00f3n de t\u00e9cnicas actorales y teatrales.<\/p>\n<p style=\"font-weight: 400;\">En tal sentido, las Escuelas de Danzas Nativas y de Teatro han iniciado su periodo de inscripci\u00f3n para asistir a estos espacios de manera gratuita.<\/p>\n<p style=\"font-weight: 400;\">ESCUELA DE DANZAS NATIVAS<\/p>\n<p style=\"font-weight: 400;\">Desde el mi\u00e9rcoles 18 de febrero se encuentra abierta la inscripci\u00f3n a la Escuela \u201cEl Trovador\u201d en Casa del Bicentenario, espacio donde se imparten las respectivas clases.<\/p>\n<p style=\"font-weight: 400;\">Los interesados podr\u00e1n consultar e inscribirse en el horario de 18 a 20, recordando que la formaci\u00f3n est\u00e1 destinada a ni\u00f1os, j\u00f3venes y adultos.<\/p>\n<p style=\"font-weight: 400;\">ESCUELA MUNICIPAL DE TEATRO<\/p>\n<p style=\"font-weight: 400;\">De igual modo, la Escuela de Teatro ha habilitado la inscripci\u00f3n para el ciclo lectivo 2026, en el Teatro Municipal en horario comercial. O tambi\u00e9n, se pueden realizar las consultas al 3777-446789. Se recuerda que la edad para ingresar es a partir de los 7 a\u00f1os.<\/p>\n<p style=\"font-weight: 400;\">Los grupos que se conformar\u00e1n son de ni\u00f1os, completando el grupo de j\u00f3venes y adultos.<\/p>\n<p style=\"font-weight: 400;\">Vale mencionar que al igual que los otros espacios art\u00edsticos culturales, a la Escuela de Teatro se puede acceder de manera gratuita.<\/p>\n<p style=\"font-weight: 400;\">\n","protected":false},"excerpt":{"rendered":"<p>La Municipalidad de Goya, a trav\u00e9s de Cultura, afianza los \u00e1mbitos de formaci\u00f3n en el aprendizaje del baile de las danzas nativas y en la adquisici\u00f3n de t\u00e9cnicas actorales y teatrales. En tal sentido, las Escuelas de Danzas Nativas y de Teatro han iniciado su periodo de inscripci\u00f3n para asistir a estos espacios de manera [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":30662,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56],"tags":[],"class_list":["post-30661","post","type-post","status-publish","format-standard","has-post-thumbnail","category-locales"],"_links":{"self":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/posts\/30661","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/comments?post=30661"}],"version-history":[{"count":0,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/posts\/30661\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/media\/30662"}],"wp:attachment":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/media?parent=30661"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/categories?post=30661"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/tags?post=30661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}