{"id":30681,"date":"2026-02-26T18:53:58","date_gmt":"2026-02-26T21:53:58","guid":{"rendered":"https:\/\/radiobitacora.com.ar\/web\/?p=30681"},"modified":"2026-02-26T18:53:58","modified_gmt":"2026-02-26T21:53:58","slug":"don-chatarrin-don-gomita-aluminica-y-el-senor-lengua-floja-quienes-son-los-empresarios-que-critico-milei","status":"publish","type":"post","link":"https:\/\/radiobitacora.com.ar\/web\/2026\/02\/26\/don-chatarrin-don-gomita-aluminica-y-el-senor-lengua-floja-quienes-son-los-empresarios-que-critico-milei\/","title":{"rendered":"\u201cDon Chatarr\u00edn\u201d, \u201cDon Gomita Alum\u00ednica\u201d y \u201cel Se\u00f1or Lengua Floja\u201d: qui\u00e9nes son los empresarios que critic\u00f3 Milei"},"content":{"rendered":"<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">El Presidente de la Naci\u00f3n,\u00a0<a title=\"https:\/\/www.infobae.com\/politica\/2026\/02\/26\/han-dejado-en-evidencia-al-sistema-corrupto-milei-apunto-contra-paolo-rocca-y-los-duenos-de-aluar-y-neumen\/\" href=\"https:\/\/www.infobae.com\/politica\/2026\/02\/26\/han-dejado-en-evidencia-al-sistema-corrupto-milei-apunto-contra-paolo-rocca-y-los-duenos-de-aluar-y-neumen\/\" target=\"_blank\" rel=\"noopener noreferrer\" data-mrf-link=\"https:\/\/www.infobae.com\/politica\/2026\/02\/26\/han-dejado-en-evidencia-al-sistema-corrupto-milei-apunto-contra-paolo-rocca-y-los-duenos-de-aluar-y-neumen\/\"><b>Javier Milei<\/b>, apunt\u00f3 esta ma\u00f1ana contra los empresarios\u00a0<b>Paolo Rocca<\/b>\u00a0(CEO del Grupo Techint),\u00a0<b>Javier Madanes Quintanilla<\/b>\u00a0(CEO de Fate y Aluar) y\u00a0<b>Roberto M\u00e9ndez<\/b>\u00a0(CEO de Neumen)<\/a>, que en las \u00faltimas semanas protagonizaron fuertes controversias.<\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\"><b>\u201cAgradezco profundamente con todo mi alma, las contribuciones enormes que han hecho Don Chatarr\u00edn de los Tubitos Caros, Don Gomita Alum\u00ednica y el Se\u00f1or Lengua Floja en los \u00faltimos 30 d\u00edas. Han dejado en evidencia al sistema corrupto que hundi\u00f3 a los argentinos de bien\u201d<\/b>, apunt\u00f3 el mandatario nacional.<\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">En un escrito titulado como \u201cBatalla cultural\u201d, el Presidente finaliz\u00f3: \u201cMuchas gracias por este gran aporte al despertar de un Pa\u00eds que, pese a estos delincuentes, quiere ser grande nuevamente\u201d.<\/p>\n<h2 class=\"header headline-class-h2 headline\">Confesi\u00f3n y pol\u00e9mica<\/h2>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">Hace dos d\u00edas,\u00a0<b>Roberto M\u00e9ndez (CEO de Neumen)<\/b>, a quien Milei lo defini\u00f3 como \u201cel Se\u00f1or Lengua Floja\u201d, reconoci\u00f3 que, antes de la desregulaci\u00f3n del mercado, los neum\u00e1ticos ten\u00edan precios elevados y que las empresas del sector lograron m\u00e1rgenes de ganancia muy altos debido a la remarcaci\u00f3n de precios, facilitada por las restricciones a las importaciones.<\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\"><b>\u201cEran car\u00edsimas, hay que reconocerlo. Yo digo que estaban robando las multinacionales y nosotros, los empresarios, porque ten\u00edamos un mercado que no era real. Nunca ganamos tanta plata como cuando nos permitieron hacer lo que est\u00e1bamos haciendo\u201d<\/b>, confes\u00f3 en una entrevista con el streaming\u00a0<i>Ahora Play<\/i>.<\/p>\n<div class=\"jwplayer-ctn\">\n<div>\n<div id=\"SCVXGZDRK5GXPAKMHMPKCQ4RIQ-custom_embed7\" class=\"jwplayer jw-reset jw-state-idle jw-stretch-uniform jw-flag-aspect-mode jw-breakpoint-5 jw-floating-dismissible jw-keep-thumbnail jw-flag-user-inactive\" tabindex=\"0\" role=\"application\" aria-label=\"Video Player - Roberto M\u00e9ndez, CEO de Neumen: &quot;Est\u00e1bamos robando con el precio de las cubiertas&quot;\" aria-describedby=\"jw-SCVXGZDRK5GXPAKMHMPKCQ4RIQ-custom_embed7-shortcuts-tooltip-explanation\" data-compass-listening=\"true\">\n<div class=\"jw-wrapper jw-reset\">\n<div class=\"jw-media jw-reset\"><\/div>\n<div class=\"jw-overlays jw-reset\">\n<div id=\"SCVXGZDRK5GXPAKMHMPKCQ4RIQ-custom_embed7_googima\" class=\"jw-plugin jw-reset jw-plugin-googima\">\n<div id=\"SCVXGZDRK5GXPAKMHMPKCQ4RIQ-custom_embed7_ad\" class=\"jw-ads-view\">\n<div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"jw-controls jw-reset\">\n<div class=\"jw-display jw-reset\">\n<div class=\"jw-display-container jw-reset\">\n<div class=\"jw-display-controls jw-reset\">\n<div class=\"jw-display-icon-container jw-display-icon-display jw-reset\">\n<div class=\"jw-icon jw-icon-display jw-button-color jw-reset\" tabindex=\"0\" role=\"button\" aria-label=\"Reproducir\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>&#8220;Soy el primero en reconocerlo. Nunca ganamos tanta plata como cuando nos permitieron hacer lo que est\u00e1bamos haciendo&#8221;, afirm\u00f3.<\/p><\/div>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">M\u00e9ndez valor\u00f3 la propuesta de Federico Sturzenegger sobre exigir a las empresas una rentabilidad acorde, cercana al 20%. \u201cEn un momento, aplic\u00e1bamos m\u00e1rgenes del 60 al 70%\u201d, afirm\u00f3.<\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">Con 42 a\u00f1os de experiencia en el rubro, M\u00e9ndez detall\u00f3 que su empresa emplea a 520 personas y cuenta con 40 sucursales en todo el pa\u00eds. Adem\u00e1s, consider\u00f3 que la rentabilidad bruta, antes de impuestos, no deber\u00eda ser inferior al 22% en Argentina, debido a que la carga impositiva local es mucho mayor que en Europa o Estados Unidos. Seg\u00fan M\u00e9ndez, ese porcentaje resulta indispensable para sostener la actividad.<\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">Al poco tiempo, Milei se hizo eco de las declaraciones y contest\u00f3 desde sus redes sociales:\u00a0<b>\u201cDedicado a los delincuentes que hacen del nacionalismo barato una bandera para robar a los argentinos de bien\u201d<\/b>.<\/p>\n<h2 class=\"header headline-class-h2 headline\">\u201cCasualidad cero\u201d<\/h2>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">Otra menci\u00f3n que hizo el presidente fue hacia\u00a0<b>Javier Madanes Quintanilla<\/b>\u00a0(CEO de Fate y Aluar), a quien nombr\u00f3 como \u201cDon Gomita Alum\u00ednica\u201d.<\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">Hace poco m\u00e1s de una semana, la empresa\u00a0<b>Fate\u00a0<\/b>anunci\u00f3 el cierre definitivo de su planta (ubicada en la localidad bonaerense de Virreyes), que dej\u00f3 como consecuencia el despido de 920 empleados y el freno de su producci\u00f3n de neum\u00e1ticos.<\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\"><b>La acci\u00f3n surgi\u00f3 en medio del debate y la discusi\u00f3n por la Reforma Laboral, algo que el gobierno no dej\u00f3 pasar por alto.<\/b>\u00a0<a title=\"https:\/\/www.infobae.com\/politica\/2026\/02\/22\/la-revancha-de-milei-por-fate-el-pronostico-del-gobierno-sobre-la-economia-y-los-cargos-sensibles-que-podria-conseguir-en-la-justicia\/\" href=\"https:\/\/www.infobae.com\/politica\/2026\/02\/22\/la-revancha-de-milei-por-fate-el-pronostico-del-gobierno-sobre-la-economia-y-los-cargos-sensibles-que-podria-conseguir-en-la-justicia\/\" target=\"_blank\" rel=\"noopener noreferrer\" data-mrf-link=\"https:\/\/www.infobae.com\/politica\/2026\/02\/22\/la-revancha-de-milei-por-fate-el-pronostico-del-gobierno-sobre-la-economia-y-los-cargos-sensibles-que-podria-conseguir-en-la-justicia\/\">\u201cCasualidad cero\u201d, sentenci\u00f3 el mandatario al enterarse del fin de la hist\u00f3rica marca<\/a>. En la misma sinton\u00eda\u00a0<a title=\"https:\/\/www.infobae.com\/politica\/2026\/02\/23\/manuel-adorni-critico-el-cierre-de-fate-fue-sugestivo-detras-de-eso-hubo-una-complicidad-con-la-vieja-politica\/\" href=\"https:\/\/www.infobae.com\/politica\/2026\/02\/23\/manuel-adorni-critico-el-cierre-de-fate-fue-sugestivo-detras-de-eso-hubo-una-complicidad-con-la-vieja-politica\/\" target=\"_blank\" rel=\"noopener noreferrer\" data-mrf-link=\"https:\/\/www.infobae.com\/politica\/2026\/02\/23\/manuel-adorni-critico-el-cierre-de-fate-fue-sugestivo-detras-de-eso-hubo-una-complicidad-con-la-vieja-politica\/\">se hab\u00eda expresado el Jefe de Gabinete,\u00a0<b>Manuel Adorni<\/b><\/a>: \u201cFue sugestivo, nosotros entendemos que detr\u00e1s de eso hubo una complicidad con la vieja pol\u00edtica\u201d.<\/p>\n<div class=\"visual__image\"><picture><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/OCSBXEL6YFD43BSJZYWK2E4MAI.jpg?auth=715653d11bfc68cd5a49ee49e04d821c64984ab03bafcf72e3a14072b15d157b&amp;smart=true&amp;width=992&amp;height=558&amp;quality=85\" media=\"(min-width: 1000px)\" \/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/OCSBXEL6YFD43BSJZYWK2E4MAI.jpg?auth=715653d11bfc68cd5a49ee49e04d821c64984ab03bafcf72e3a14072b15d157b&amp;smart=true&amp;width=768&amp;height=432&amp;quality=85\" media=\"(min-width: 768px)\" \/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/OCSBXEL6YFD43BSJZYWK2E4MAI.jpg?auth=715653d11bfc68cd5a49ee49e04d821c64984ab03bafcf72e3a14072b15d157b&amp;smart=true&amp;width=577&amp;height=325&amp;quality=85\" media=\"(min-width: 580px)\" \/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/OCSBXEL6YFD43BSJZYWK2E4MAI.jpg?auth=715653d11bfc68cd5a49ee49e04d821c64984ab03bafcf72e3a14072b15d157b&amp;smart=true&amp;width=420&amp;height=236&amp;quality=85\" media=\"(min-width: 350px)\" \/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/OCSBXEL6YFD43BSJZYWK2E4MAI.jpg?auth=715653d11bfc68cd5a49ee49e04d821c64984ab03bafcf72e3a14072b15d157b&amp;smart=true&amp;width=350&amp;height=197&amp;quality=85\" media=\"(min-width: 80px)\" \/><img loading=\"lazy\" decoding=\"async\" class=\"global-image\" src=\"https:\/\/www.infobae.com\/resizer\/v2\/OCSBXEL6YFD43BSJZYWK2E4MAI.jpg?auth=715653d11bfc68cd5a49ee49e04d821c64984ab03bafcf72e3a14072b15d157b&amp;smart=true&amp;width=350&amp;height=197&amp;quality=85\" alt=\"Instalaciones de Fate, empresa productora\" width=\"1920\" height=\"1080\" \/><\/picture>Instalaciones de Fate, empresa productora de neum\u00e1ticos, y silos de Aluar, compa\u00f1\u00eda l\u00edder en aluminio, reflejando dos importantes sectores industriales. ( bertolotti.luciano@, Andr\u00e9s Sanguinetti)<\/div>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">Sin embargo, no fue el \u00fanico cruce. El \u00faltimo lunes,\u00a0<b>el Gobierno elimin\u00f3 el arancel antidumping del 28% aplicado a las hojas de aluminio importadas desde China<\/b>. Esta medida, solicitada en 2020 por\u00a0<b>Aluar<\/b>\u00a0\u2014el mayor productor nacional del sector y tambi\u00e9n propiedad de Madanes Quintanilla\u2014, hab\u00eda sido establecida durante la gesti\u00f3n de\u00a0<b>Alberto Fern\u00e1ndez<\/b>\u00a0por un per\u00edodo de cinco a\u00f1os, con vencimiento previsto para el 5 de marzo.<\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">Luego de revisar un informe t\u00e9cnico elaborado por el \u00e1rea de Comercio Exterior, las autoridades concluyeron que no se detecta margen de dumping en las exportaciones del producto bajo an\u00e1lisis hacia la Argentina.<\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">Con el vencimiento del arancel,\u00a0<b>Aluar solicit\u00f3 la reapertura del an\u00e1lisis para extender la medida, pero el Gobierno rechaz\u00f3 el pedido.<\/b>\u00a0La compa\u00f1\u00eda puede apelar la decisi\u00f3n ante el Ministerio de Econom\u00eda y, en \u00faltima instancia, ante la Jefatura de Gabinete. Solo despu\u00e9s de agotar estas v\u00edas administrativas podr\u00eda recurrir a la justicia.<\/p>\n<h2 class=\"header headline-class-h2 headline\">La disputa por la apertura de las importaciones<\/h2>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">\u201cDon Chatarr\u00edn de los Tubitos Caros\u201d es la referencia de Milei hacia el CEO del Grupo Techint,\u00a0<b>Paolo Rocca.\u00a0<\/b>Es que, a fines de enero, la adjudicaci\u00f3n a la empresa india\u00a0<b>Welspun<\/b>\u00a0para proveer tubos para el gasoducto entre\u00a0<b>Vaca Muerta<\/b>\u00a0y\u00a0<b>R\u00edo Negro<\/b>\u00a0provoc\u00f3 un enfrentamiento p\u00fablico entre ambos dirigentes.<\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">Javier Milei respald\u00f3 la apertura de importaciones y critic\u00f3 a quienes se oponen, sugiriendo que las objeciones responden a intereses particulares. \u201cLa nueva Argentina\u201d, afirm\u00f3 el presidente. \u201cSi ves \u2018periodistas\u2019, \u2018economistas\u2019 y pol\u00edticos hablando de la industria del acero y de los supuestos perjuicios de la apertura, ya sab\u00e9s qui\u00e9n les paga&#8230;\u201d, se\u00f1al\u00f3.<\/p>\n<div class=\"visual__image\"><picture><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/4XI6HDUOLK5KAQOXR7KE75QGIM.jpg?auth=79ce19769cca21a4524b89543dc5cf8395885946e77fc7bd7ef4d1ddc6f4e316&amp;smart=true&amp;width=992&amp;height=662&amp;quality=85\" media=\"(min-width: 1000px)\" \/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/4XI6HDUOLK5KAQOXR7KE75QGIM.jpg?auth=79ce19769cca21a4524b89543dc5cf8395885946e77fc7bd7ef4d1ddc6f4e316&amp;smart=true&amp;width=768&amp;height=513&amp;quality=85\" media=\"(min-width: 768px)\" \/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/4XI6HDUOLK5KAQOXR7KE75QGIM.jpg?auth=79ce19769cca21a4524b89543dc5cf8395885946e77fc7bd7ef4d1ddc6f4e316&amp;smart=true&amp;width=577&amp;height=385&amp;quality=85\" media=\"(min-width: 580px)\" \/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/4XI6HDUOLK5KAQOXR7KE75QGIM.jpg?auth=79ce19769cca21a4524b89543dc5cf8395885946e77fc7bd7ef4d1ddc6f4e316&amp;smart=true&amp;width=420&amp;height=280&amp;quality=85\" media=\"(min-width: 350px)\" \/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/4XI6HDUOLK5KAQOXR7KE75QGIM.jpg?auth=79ce19769cca21a4524b89543dc5cf8395885946e77fc7bd7ef4d1ddc6f4e316&amp;smart=true&amp;width=350&amp;height=234&amp;quality=85\" media=\"(min-width: 80px)\" \/><img loading=\"lazy\" decoding=\"async\" class=\"global-image\" src=\"https:\/\/www.infobae.com\/resizer\/v2\/4XI6HDUOLK5KAQOXR7KE75QGIM.jpg?auth=79ce19769cca21a4524b89543dc5cf8395885946e77fc7bd7ef4d1ddc6f4e316&amp;smart=true&amp;width=350&amp;height=234&amp;quality=85\" alt=\"Personal trabaja en la construcci\u00f3n\" width=\"800\" height=\"534\" \/><\/picture>Personal trabaja en la construcci\u00f3n de un gasoducto para transportar gas natural desde la formaci\u00f3n Vaca Muerta (Imagen de archivo \/ Reuters \/ Martin Cossarini)<\/div>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">Posteriormente, dirigi\u00f3 sus cr\u00edticas a Rocca al cuestionar a quienes defienden \u201ca Don Chatarr\u00edn de los tubitos caros\u201d. De esta manera,\u00a0<b>el Gobierno decidi\u00f3 no aplicar medidas antidumping y descart\u00f3 establecer barreras comerciales adicionales.<\/b><\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">A inicios de este mes,\u00a0<a title=\"https:\/\/www.infobae.com\/economia\/2026\/02\/04\/la-carta-de-paolo-rocca-tras-el-conflicto-con-el-gobierno-por-la-licitacion-del-gasoducto\/\" href=\"https:\/\/www.infobae.com\/economia\/2026\/02\/04\/la-carta-de-paolo-rocca-tras-el-conflicto-con-el-gobierno-por-la-licitacion-del-gasoducto\/\" target=\"_blank\" rel=\"noopener noreferrer\" data-mrf-link=\"https:\/\/www.infobae.com\/economia\/2026\/02\/04\/la-carta-de-paolo-rocca-tras-el-conflicto-con-el-gobierno-por-la-licitacion-del-gasoducto\/\">Rocca public\u00f3 una carta<\/a>\u00a0en la que respondi\u00f3 a las cr\u00edticas por anunciar que presentar\u00eda una denuncia antidumping contra la empresa india Welspun, adjudicataria del contrato. Adem\u00e1s, defendi\u00f3 la importancia de la industria nacional y pidi\u00f3 establecer un di\u00e1logo con la administraci\u00f3n libertaria para fortalecer la competitividad del sector industrial.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Presidente de la Naci\u00f3n,\u00a0Javier Milei, apunt\u00f3 esta ma\u00f1ana contra los empresarios\u00a0Paolo Rocca\u00a0(CEO del Grupo Techint),\u00a0Javier Madanes Quintanilla\u00a0(CEO de Fate y Aluar) y\u00a0Roberto M\u00e9ndez\u00a0(CEO de Neumen), que en las \u00faltimas semanas protagonizaron fuertes controversias. \u201cAgradezco profundamente con todo mi alma, las contribuciones enormes que han hecho Don Chatarr\u00edn de los Tubitos Caros, Don Gomita Alum\u00ednica [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":30682,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[65],"tags":[],"class_list":["post-30681","post","type-post","status-publish","format-standard","has-post-thumbnail","category-economia"],"_links":{"self":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/posts\/30681","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/comments?post=30681"}],"version-history":[{"count":0,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/posts\/30681\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/media\/30682"}],"wp:attachment":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/media?parent=30681"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/categories?post=30681"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/tags?post=30681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}