{"id":30696,"date":"2026-02-26T19:22:47","date_gmt":"2026-02-26T22:22:47","guid":{"rendered":"https:\/\/radiobitacora.com.ar\/web\/?p=30696"},"modified":"2026-02-26T19:22:47","modified_gmt":"2026-02-26T22:22:47","slug":"algunos-vamos-a-quedar-en-el-camino-pero-es-el-precio-que-hay-que-pagar-para-tener-una-argentina-normal-reconocio-el-presidente-de-la-camara-de-comercio","status":"publish","type":"post","link":"https:\/\/radiobitacora.com.ar\/web\/2026\/02\/26\/algunos-vamos-a-quedar-en-el-camino-pero-es-el-precio-que-hay-que-pagar-para-tener-una-argentina-normal-reconocio-el-presidente-de-la-camara-de-comercio\/","title":{"rendered":"\u201cAlgunos vamos a quedar en el camino, pero es el precio que hay que pagar para tener una Argentina normal\u201d, reconoci\u00f3 el presidente de la C\u00e1mara de Comercio"},"content":{"rendered":"<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">\u201c<b>Algunos vamos a quedar en el camino, pero ese es el precio que hay que pagar para que nuestros nietos, nuestros hijos, tengan una Argentina normal<\/b>\u201d, asegur\u00f3 el presidente de la\u00a0<b>C\u00e1mara Argentina de Comercio y Servicios<\/b>,\u00a0<b>Mario Grinman<\/b>, al analizar el panorama econ\u00f3mico que enfrenta el sector.<\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">La declaraci\u00f3n se dio tras la reuni\u00f3n del\u00a0<b>G6<\/b>\u00a0con el jefe de Gabinete,\u00a0<b>Manuel Adorni<\/b>, y refleja el estado de \u00e1nimo de los principales referentes empresarios ante los desaf\u00edos del pa\u00eds.<\/p>\n<h3 class=\"header headline-class-h3 headline\">El G6 y su encuentro con el jefe de Gabinete Manuel Adorni<\/h3>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">La reuni\u00f3n entre los integrantes del\u00a0<b>G6<\/b>\u00a0(Grupo de los 6) y el jefe de Gabinete,\u00a0<b>Manuel Adorni<\/b>, se concret\u00f3 tras varios intentos postergados por cuestiones de agenda. Seg\u00fan explic\u00f3\u00a0<b>Grinman<\/b>, el encuentro dur\u00f3 casi una hora y media y permiti\u00f3 conversar sobre la realidad de todos los sectores que integran el grupo, en un contexto marcado por la heterogeneidad y las dificultades.<\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">El dirigente remarc\u00f3 en di\u00e1logo con el periodista Eduardo Feinmann\u00a0<i>en radio Mitre<\/i>\u00a0que la situaci\u00f3n econ\u00f3mica no es sencilla para ninguna de las ramas representadas: \u201cNo es f\u00e1cil, no se est\u00e1 atravesando un momento f\u00e1cil, con se\u00f1ales interesantes en el crecimiento econ\u00f3mico, pero tambi\u00e9n hay otras cuestiones un poquito duras para los distintos sectores,\u00a0<b>pero entendiendo que este es el camino y que estamos dispuestos a apoyarlo con todo el sacrificio\u00a0<\/b>que se necesita para salir adelante\u201d.<\/p>\n<div class=\"visual__image\"><picture><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/DT7ZWD2UJBAG5IJJMVXWHVOSPI.jpg?auth=6286ab1ef9cef4f77d89d20cf4a9455ddd2b3dca25c582f430bad497ba006feb&amp;smart=true&amp;width=992&amp;height=661&amp;quality=85\" media=\"(min-width: 1000px)\" \/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/DT7ZWD2UJBAG5IJJMVXWHVOSPI.jpg?auth=6286ab1ef9cef4f77d89d20cf4a9455ddd2b3dca25c582f430bad497ba006feb&amp;smart=true&amp;width=768&amp;height=512&amp;quality=85\" media=\"(min-width: 768px)\" \/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/DT7ZWD2UJBAG5IJJMVXWHVOSPI.jpg?auth=6286ab1ef9cef4f77d89d20cf4a9455ddd2b3dca25c582f430bad497ba006feb&amp;smart=true&amp;width=577&amp;height=385&amp;quality=85\" media=\"(min-width: 580px)\" \/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/DT7ZWD2UJBAG5IJJMVXWHVOSPI.jpg?auth=6286ab1ef9cef4f77d89d20cf4a9455ddd2b3dca25c582f430bad497ba006feb&amp;smart=true&amp;width=420&amp;height=280&amp;quality=85\" media=\"(min-width: 350px)\" \/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/DT7ZWD2UJBAG5IJJMVXWHVOSPI.jpg?auth=6286ab1ef9cef4f77d89d20cf4a9455ddd2b3dca25c582f430bad497ba006feb&amp;smart=true&amp;width=350&amp;height=233&amp;quality=85\" media=\"(min-width: 80px)\" \/><img loading=\"lazy\" decoding=\"async\" class=\"global-image\" src=\"https:\/\/www.infobae.com\/resizer\/v2\/DT7ZWD2UJBAG5IJJMVXWHVOSPI.jpg?auth=6286ab1ef9cef4f77d89d20cf4a9455ddd2b3dca25c582f430bad497ba006feb&amp;smart=true&amp;width=350&amp;height=233&amp;quality=85\" alt=\"Ayer, la reuni\u00f3n del G6\" width=\"1920\" height=\"1280\" \/><\/picture>Ayer, la reuni\u00f3n del G6 con el jefe de Gabinete Manuel Adorni. Mario Grinman es el segundo de la foto, de izquierda a derecha<\/div>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">En el intercambio,\u00a0<b>Adorni<\/b> garantiz\u00f3 que el modelo econ\u00f3mico del Gobierno no va a repetir l\u00f3gicas de parches sectoriales: \u201cLo que \u00e9l nos asegur\u00f3, que el modelo que est\u00e1 implementando este gobierno no va tambi\u00e9n, como ha sucedido con otros gobiernos, que van a ir, que apuntan a sectores determinados. Hay un problema en un sector, va y soluciona ese problema, y despu\u00e9s esa soluci\u00f3n genera un problema en otro sector y vuelve a atacar. Eso es imposible hacerlo. Hay que buscarle la vuelta para que la Argentina entre en una estructura de bonanza\u201d.<\/p>\n<h3 class=\"header headline-class-h3 headline\">Diagn\u00f3stico del sector comercio y servicios: ca\u00edda del consumo y amesetamiento<\/h3>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\"><b>Grinman<\/b>\u00a0defendi\u00f3 la posici\u00f3n del sector comercio y servicios en el contexto actual, admitiendo que atraviesan una etapa dif\u00edcil: \u201c<b>No la estoy pasando bien, porque el consumo ha ca\u00eddo, pero tambi\u00e9n tiene sus explicaciones<\/b>\u201d. Record\u00f3 que durante 2023, con el \u201cplan Platita\u201d, se vivi\u00f3 una realidad distorsionada: \u201c<b>En su momento, en el a\u00f1o veintitr\u00e9s, hab\u00eda anab\u00f3licos, que era el plan Platita<\/b>. Entonces, todos sab\u00edamos que eso era la isla de la fantas\u00eda, que no pod\u00eda durar, pero todo eso dej\u00f3 remesones\u201d.<\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">Sobre la situaci\u00f3n presente, rechaz\u00f3 la idea de un parate total y prefiri\u00f3 hablar de un \u201c<b>amesetamiento<\/b>\u201d. \u201cLo que hay es un amesetamiento, y ven\u00edamos con una inercia. El consumo volaba, porque la gente sab\u00eda que el dinero en el bolsillo le quemaba y hab\u00eda que salir r\u00e1pidamente a desprenderse. Hoy eso no sucede, los precios est\u00e1n estables y, es cierto, el consumo ha mermado, pero las expectativas, de a poquito, sabemos que esto va a funcionar\u201d, afirm\u00f3\u00a0<b>Grinman<\/b>.<\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">Consultado por la cantidad de empresas afectadas, el titular de la\u00a0<b>C\u00e1mara Argentina de Comercio y Servicios<\/b>\u00a0se\u00f1al\u00f3: \u201cNo existen cifras exactas, porque ni siquiera los organismos lo pueden tener, porque muchas empresas cierran, no avisan que cierran, porque son chiquitas, atendidas por sus propios due\u00f1os. No hay despido de personal. Nosotros, el sector comercio, que s\u00ed medimos, entre las altas y bajas de personal, no hay ca\u00edda, eso se mantiene estable, pero seguramente hay sectores que cierran\u201d.<\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">Distingui\u00f3 la situaci\u00f3n del comercio respecto de la industria y la construcci\u00f3n, m\u00e1s impactadas por la falta de obra p\u00fablica: \u201cEn la industria pueda haber, en la construcci\u00f3n tambi\u00e9n, que est\u00e1 mucho m\u00e1s afectada por la falta de obra p\u00fablica, pero en el sector comercio, no, nosotros lo medimos y eso no se ve\u201d.<\/p>\n<h3 class=\"header headline-class-h3 headline\">Pol\u00edticas sectoriales, costo social y futuro: \u201cEse es el precio que hay que pagar\u201d<\/h3>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">Uno de los ejes m\u00e1s destacados del mensaje de\u00a0<b>Grinman<\/b>\u00a0fue la advertencia sobre el costo social que implica la recuperaci\u00f3n: \u201c<b>Nosotros somos conscientes, es duro reconocerlo, que algunos vamos a quedar en el camino, pero ese es el precio, y ese es el precio que hay que pagar para que nuestros nietos, nuestros hijos, tengan una Argentina normal, un pa\u00eds que progrese, con futuro, yo creo que vale la pena\u201d<\/b>.<\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">A la vez, critic\u00f3 las soluciones que se aplican de manera aislada a distintos sectores y pidi\u00f3 apostar a reformas estructurales: \u201cNo se puede ir con parches para un sector s\u00ed y para el otro no. Y nosotros coincidimos, a pesar de que conocemos la realidad de nuestro sector\u201d.<\/p>\n<h3 class=\"header headline-class-h3 headline\">Importaciones, tipo de cambio y contrabando: los desaf\u00edos estructurales<\/h3>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">En relaci\u00f3n al comercio exterior,\u00a0<b>Grinman<\/b>\u00a0describi\u00f3 el dilema de la econom\u00eda argentina: \u201cEl sector exportador siempre quiere un d\u00f3lar recontra alto, y el sector importador quiere un d\u00f3lar m\u00e1s bajo. Esa es una realidad\u201d. Adem\u00e1s, remarc\u00f3 que la Argentina sigue siendo \u201cel tercer pa\u00eds del mundo m\u00e1s cerrado en t\u00e9rminos de aranceles\u201d, y que lo que se importa hoy representa apenas \u201cel dos por ciento o el tres por ciento del consumo\u201d.<\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">El dirigente tambi\u00e9n puso el foco en el peso de la carga tributaria y las limitaciones del Estado para reducir el gasto p\u00fablico: \u201cTodav\u00eda hay una carga tributaria muy alta en la Argentina, que eso no es f\u00e1cil bajar, porque el Gobierno tiene l\u00edmites para bajar el gasto p\u00fablico. El ochenta por ciento del gasto p\u00fablico son cuestiones sociales, jubilados, seguridad, salud, educaci\u00f3n, que eso ya no se puede tocar m\u00e1s\u201d.<\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">Sobre las proyecciones de crecimiento,\u00a0<b>Grinman<\/b>\u00a0se mostr\u00f3 optimista: \u201cLa proyecci\u00f3n para este a\u00f1o, algunos hablan del cuatro por ciento. Nosotros somos un poco m\u00e1s optimistas, pensamos que en el a\u00f1o veintis\u00e9is la econom\u00eda en la Argentina puede estar arriba del cinco por ciento de crecimiento\u201d.<\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">Finalmente, abord\u00f3 el problema del contrabando, en especial en el mercado de celulares: \u201cUno de cada tres celulares que se venden en la Argentina son de contrabando. Es una frontera tremenda la que tiene la Argentina, y las posibilidades de combatir eso tambi\u00e9n son bastante limitadas. Pero esa es una realidad que influye, que afecta, que el Gobierno lo sabe y tiene que tomar las medidas de consecuencia\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cAlgunos vamos a quedar en el camino, pero ese es el precio que hay que pagar para que nuestros nietos, nuestros hijos, tengan una Argentina normal\u201d, asegur\u00f3 el presidente de la\u00a0C\u00e1mara Argentina de Comercio y Servicios,\u00a0Mario Grinman, al analizar el panorama econ\u00f3mico que enfrenta el sector. La declaraci\u00f3n se dio tras la reuni\u00f3n del\u00a0G6\u00a0con el [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":30697,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[65],"tags":[],"class_list":["post-30696","post","type-post","status-publish","format-standard","has-post-thumbnail","category-economia"],"_links":{"self":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/posts\/30696","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/comments?post=30696"}],"version-history":[{"count":0,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/posts\/30696\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/media\/30697"}],"wp:attachment":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/media?parent=30696"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/categories?post=30696"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/tags?post=30696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}