{"id":32224,"date":"2026-04-09T11:38:49","date_gmt":"2026-04-09T14:38:49","guid":{"rendered":"https:\/\/radiobitacora.com.ar\/web\/?p=32224"},"modified":"2026-04-09T11:38:49","modified_gmt":"2026-04-09T14:38:49","slug":"prefectura-amplia-puntos-de-verificacion-y-agiliza-tramites","status":"publish","type":"post","link":"https:\/\/radiobitacora.com.ar\/web\/2026\/04\/09\/prefectura-amplia-puntos-de-verificacion-y-agiliza-tramites\/","title":{"rendered":"PREFECTURA AMPL\u00cdA PUNTOS DE VERIFICACI\u00d3N Y AGILIZA TR\u00c1MITES"},"content":{"rendered":"<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">El prefecto Sebasti\u00e1n Marcelo Regondi, jefe de Prefectura, inform\u00f3 que, de cara a la Fiesta Nacional del Surub\u00ed, iniciaron las verificaciones y se busca ampliar los d\u00edas para tal actividad.\u00a0&#8220;Esto es un sistema de mejora continua&#8221;, afirm\u00f3.<\/p>\n<p style=\"font-weight: 400;\">Una de las principales novedades es la ampliaci\u00f3n de los puntos de verificaci\u00f3n. Desde el 1 de abril los pescadores pueden realizar la verificaci\u00f3n de sus embarcaciones en diversas dependencias de Prefectura, abarcando un \u00e1rea geogr\u00e1fica considerable. A lo que estaba previsto, \u201cse ampli\u00f3\u201d: \u201cIba a ser en la jurisdicci\u00f3n de Prefectura desde zona de Esquina a Pilcomayo, pero ahora se extiende un poco m\u00e1s, lo vamos a hacer en jurisdicci\u00f3n de Alto Uruguay y Alto Paran\u00e1 tambi\u00e9n hasta Puerto Andresito&#8221;, detall\u00f3 Regondi, destacando que \u201cel pescador podr\u00e1 acercarse a la Prefectura con la embarcaci\u00f3n y hacer la verificaci\u00f3n&#8221;, explic\u00f3 el Prefecto.<\/p>\n<p style=\"font-weight: 400;\">Si bien la verificaci\u00f3n inicial se podr\u00e1 realizar en estas zonas, los pescadores deber\u00e1n luego presentar el acta firmada en la dependencia de Goya o en los puntos oficiales que se dar\u00e1n a conocer pr\u00f3ximamente, para recibir la oblea de control que se adhiere a la lancha.<\/p>\n<p style=\"font-weight: 400;\">El objetivo es optimizar los procesos bas\u00e1ndose en los problemas del a\u00f1o pasado y agilizar los controles previos al inicio del concurso.<\/p>\n<p style=\"font-weight: 400;\">Esta ampliaci\u00f3n busca descongestionar los puntos de verificaci\u00f3n en Goya y hacer el proceso m\u00e1s din\u00e1mico. &#8220;Sabemos que todo est\u00e1 colmado y buscamos la agilidad en los controles para que el pescador pueda disfrutar del momento que viene a Goya y que no sea un percance&#8221;, se\u00f1al\u00f3.<\/p>\n<p style=\"font-weight: 400;\">La zona geogr\u00e1fica comprendida para realizar el mencionado tr\u00e1mite, con el prop\u00f3sito de facilitar y agilizar el cumplimiento del requisito, a partir de esta decisi\u00f3n anunciada desde Prefectura, abarca las provincias de Formosa, Chaco, Misiones y Corrientes.<\/p>\n<p style=\"font-weight: 400;\">DOCUMENTACI\u00d3N Y REQUISITOS OBLIGATORIOS<\/p>\n<p style=\"font-weight: 400;\">Regondi tambi\u00e9n inform\u00f3 sobre la documentaci\u00f3n necesaria para la verificaci\u00f3n:<\/p>\n<p style=\"font-weight: 400;\">Certificado de Matr\u00edcula o Constancia de Matr\u00edcula: Acredita la propiedad de la lancha y debe coincidir con los datos del propietario.<\/p>\n<p style=\"font-weight: 400;\">Habilitaci\u00f3n N\u00e1utica Deportiva: Debe estar vigente y coincidir con los datos de la matr\u00edcula.<\/p>\n<p style=\"font-weight: 400;\">Permiso Certificado por Escribano: En caso de que el timonel no sea el propietario de la lancha, se requiere un permiso que lo autorice a conducirla.<\/p>\n<p style=\"font-weight: 400;\">Adem\u00e1s, el prefecto record\u00f3 que los elementos de seguridad son los establecidos por la ordenanza respectiva, pero por su disposici\u00f3n ser\u00e1 obligatorio el uso de chalecos salvavidas, como medida de seguridad fundamental, \u201cespecialmente considerando el c\u00famulo de embarcaciones\u201d.<\/p>\n<p style=\"font-weight: 400;\">El prefecto hizo un llamado a quienes tengan alguna irregularidad documental a acercarse con tiempo a la Prefectura para recibir asesoramiento y solucionar cualquier inconveniente antes de la competencia, garantizando as\u00ed una participaci\u00f3n exitosa en la Fiesta Nacional del Surub\u00ed.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El prefecto Sebasti\u00e1n Marcelo Regondi, jefe de Prefectura, inform\u00f3 que, de cara a la Fiesta Nacional del Surub\u00ed, iniciaron las verificaciones y se busca ampliar los d\u00edas para tal actividad.\u00a0&#8220;Esto es un sistema de mejora continua&#8221;, afirm\u00f3. Una de las principales novedades es la ampliaci\u00f3n de los puntos de verificaci\u00f3n. Desde el 1 de abril [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56],"tags":[],"class_list":["post-32224","post","type-post","status-publish","format-standard","category-locales"],"_links":{"self":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/posts\/32224","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/comments?post=32224"}],"version-history":[{"count":0,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/posts\/32224\/revisions"}],"wp:attachment":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/media?parent=32224"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/categories?post=32224"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/tags?post=32224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}