{"id":32349,"date":"2026-04-12T14:52:00","date_gmt":"2026-04-12T17:52:00","guid":{"rendered":"https:\/\/radiobitacora.com.ar\/web\/?p=32349"},"modified":"2026-04-12T14:52:00","modified_gmt":"2026-04-12T17:52:00","slug":"dispositivo-medico-asistencial-en-punta-maruchas","status":"publish","type":"post","link":"https:\/\/radiobitacora.com.ar\/web\/2026\/04\/12\/dispositivo-medico-asistencial-en-punta-maruchas\/","title":{"rendered":"DISPOSITIVO M\u00c9DICO ASISTENCIAL EN PUNTA MARUCHAS"},"content":{"rendered":"<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">La Municipalidad de Goya despleg\u00f3 el operativo m\u00e9dico en zona rural con el objetivo de reforzar la Atenci\u00f3n Primaria de la Salud de las familias del lugar. Cuarenta y siete pacientes recibieron atenci\u00f3n este jueves.<\/p>\n<p style=\"font-weight: 400;\">El equipo de Salud de la Municipalidad estuvo integrado por el Dr. Marcelo Rojas y el personal de enfermer\u00eda y farmacia. Realizaron las siguientes atenciones: Examen psicof\u00edsicos escolares, control y completamiento del calendario de vacunaci\u00f3n de inicio de clases, entrega de medicaci\u00f3n para pacientes con hipertensi\u00f3n y diabetes, tratamientos antiparasitarios.<\/p>\n<p style=\"font-weight: 400;\">El objetivo principal es trabajar en territorio, acercando la salud a cada rinc\u00f3n y reafirmando el compromiso con las familias rurales, garantizando una atenci\u00f3n integral y cercana.<\/p>\n<p style=\"font-weight: 400;\">El operativo cont\u00f3 con la colaboraci\u00f3n de la Delegaci\u00f3n Goya de Desarrollo Social.<\/p>\n<p style=\"font-weight: 400;\">PR\u00d3XIMO DISPOSITIVO<\/p>\n<p style=\"font-weight: 400;\">Id\u00e9ntico operativo se desarrollar\u00e1 la pr\u00f3xima semana, el martes 14, desde las 9 horas, en la 3\u00aa Secci\u00f3n, Cocalito, en el domicilio de do\u00f1a Eca.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Municipalidad de Goya despleg\u00f3 el operativo m\u00e9dico en zona rural con el objetivo de reforzar la Atenci\u00f3n Primaria de la Salud de las familias del lugar. Cuarenta y siete pacientes recibieron atenci\u00f3n este jueves. El equipo de Salud de la Municipalidad estuvo integrado por el Dr. Marcelo Rojas y el personal de enfermer\u00eda y [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":32350,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56],"tags":[],"class_list":["post-32349","post","type-post","status-publish","format-standard","has-post-thumbnail","category-locales"],"_links":{"self":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/posts\/32349","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/comments?post=32349"}],"version-history":[{"count":0,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/posts\/32349\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/media\/32350"}],"wp:attachment":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/media?parent=32349"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/categories?post=32349"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/tags?post=32349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}