{"id":33832,"date":"2026-05-28T08:44:22","date_gmt":"2026-05-28T11:44:22","guid":{"rendered":"https:\/\/radiobitacora.com.ar\/web\/?p=33832"},"modified":"2026-05-28T08:46:25","modified_gmt":"2026-05-28T11:46:25","slug":"voces-callejeras-estefania-arce-conto-como-crece-goya-grow-y-el-impacto-del-cannabis-medicinal","status":"publish","type":"post","link":"https:\/\/radiobitacora.com.ar\/web\/2026\/05\/28\/voces-callejeras-estefania-arce-conto-como-crece-goya-grow-y-el-impacto-del-cannabis-medicinal\/","title":{"rendered":"VOCES CALLEJERAS: ESTEFAN\u00cdA ARCE CONT\u00d3 C\u00d3MO CRECE GOYA GROW Y EL IMPACTO DEL CANNABIS MEDICINAL"},"content":{"rendered":"<p class=\"isSelectedEnd\">En una nueva edici\u00f3n del programa \u201cVoces Callejeras\u201d, Estefan\u00eda Arce, licenciada en Nutrici\u00f3n y propietaria de Goya Grow, visit\u00f3 el estudio para compartir su experiencia en el mundo del cannabis medicinal, el crecimiento de su emprendimiento y la importancia de la informaci\u00f3n y la concientizaci\u00f3n sobre el uso responsable de la planta.<\/p>\n<p class=\"isSelectedEnd\">Durante la entrevista, Arce habl\u00f3 sobre c\u00f3mo comenz\u00f3 su camino en el cannabis terap\u00e9utico a partir de una experiencia personal relacionada con dolores f\u00edsicos durante la pandemia. A partir de all\u00ed, comenz\u00f3 a interiorizarse en el tema mediante diplomaturas, cursos y capacitaciones sobre fitopreparados y endocannabinolog\u00eda.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-33833\" src=\"https:\/\/radiobitacora.com.ar\/web\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-28-at-8.41.50-AM-2.jpeg\" alt=\"\" width=\"1280\" height=\"960\" srcset=\"https:\/\/radiobitacora.com.ar\/web\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-28-at-8.41.50-AM-2.jpeg 1280w, https:\/\/radiobitacora.com.ar\/web\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-28-at-8.41.50-AM-2-560x420.jpeg 560w, https:\/\/radiobitacora.com.ar\/web\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-28-at-8.41.50-AM-2-80x60.jpeg 80w, https:\/\/radiobitacora.com.ar\/web\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-28-at-8.41.50-AM-2-696x522.jpeg 696w, https:\/\/radiobitacora.com.ar\/web\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-28-at-8.41.50-AM-2-1068x801.jpeg 1068w, https:\/\/radiobitacora.com.ar\/web\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-28-at-8.41.50-AM-2-265x198.jpeg 265w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<p class=\"isSelectedEnd\">La emprendedora explic\u00f3 que muchas personas recurren al aceite de cannabis para aliviar dolores cr\u00f3nicos, Parkinson, epilepsia y otras patolog\u00edas, siempre bajo supervisi\u00f3n m\u00e9dica. Adem\u00e1s, destac\u00f3 la importancia de realizar un acompa\u00f1amiento responsable en cada caso y trabajar en conjunto con profesionales especializados.<\/p>\n<p class=\"isSelectedEnd\">Uno de los momentos m\u00e1s emotivos de la entrevista fue cuando desde el programa agradecieron a Estefan\u00eda por haber ayudado a conseguir aceite de cannabis para una persona con Parkinson, resaltando el alivio que gener\u00f3 en su tratamiento diario.<\/p>\n<p class=\"isSelectedEnd\">Arce tambi\u00e9n coment\u00f3 que en Goya Grow no solo se comercializan productos relacionados con el cannabis medicinal, sino tambi\u00e9n herramientas para cultivo indoor y outdoor, fertilizantes, preventivos para plagas, art\u00edculos de jardiner\u00eda y productos de tabaquer\u00eda. Adem\u00e1s, se\u00f1al\u00f3 que cuentan con habilitaci\u00f3n legal para vender esquejes y semillas de cannabis.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-33834\" src=\"https:\/\/radiobitacora.com.ar\/web\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-28-at-8.41.50-AM-1.jpeg\" alt=\"\" width=\"1280\" height=\"960\" srcset=\"https:\/\/radiobitacora.com.ar\/web\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-28-at-8.41.50-AM-1.jpeg 1280w, https:\/\/radiobitacora.com.ar\/web\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-28-at-8.41.50-AM-1-560x420.jpeg 560w, https:\/\/radiobitacora.com.ar\/web\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-28-at-8.41.50-AM-1-80x60.jpeg 80w, https:\/\/radiobitacora.com.ar\/web\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-28-at-8.41.50-AM-1-696x522.jpeg 696w, https:\/\/radiobitacora.com.ar\/web\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-28-at-8.41.50-AM-1-1068x801.jpeg 1068w, https:\/\/radiobitacora.com.ar\/web\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-28-at-8.41.50-AM-1-265x198.jpeg 265w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<p class=\"isSelectedEnd\">En otro tramo de la charla, explic\u00f3 el funcionamiento del Reprocann y la Ley 27.350, normativa que regula el uso medicinal del cannabis en Argentina. Seg\u00fan detall\u00f3, desde su espacio asesoran a quienes desean acceder al autocultivo legal y trabajar de manera regulada.<\/p>\n<p class=\"isSelectedEnd\">La propietaria de Goya Grow tambi\u00e9n destac\u00f3 la realizaci\u00f3n de talleres informativos y charlas abiertas junto a asociaciones civiles, buscando combatir la desinformaci\u00f3n y la estigmatizaci\u00f3n que a\u00fan existe alrededor del cannabis.<\/p>\n<p class=\"isSelectedEnd\">Sobre el crecimiento del emprendimiento, Estefan\u00eda se\u00f1al\u00f3 que actualmente realizan env\u00edos a distintas localidades de Corrientes y el litoral, consolidando a Goya Grow como un espacio de referencia para quienes buscan asesoramiento, productos y acompa\u00f1amiento en el tema.<\/p>\n<p class=\"isSelectedEnd\">Finalmente, agradeci\u00f3 la invitaci\u00f3n al programa y dej\u00f3 abierta la posibilidad de continuar realizando encuentros y espacios de informaci\u00f3n para la comunidad.<\/p>\n<p>Goya Grow se encuentra ubicado en 9 de Julio 111 de la ciudad de Goya y atiende tanto de manera presencial como a trav\u00e9s de sus redes sociales.<\/p>\n<p>Mira la entrevista completa aca :\u00a0<a href=\"https:\/\/www.youtube.com\/live\/zgaAurNtVYo?si=xk4R05lT6Rm5zTj6\">https:\/\/www.youtube.com\/live\/zgaAurNtVYo?si=xk4R05lT6Rm5zTj6<\/a><\/p>\n<div dir=\"auto\">FUENTE : Multiplataformas Radio, Tv y Streaming de Goya<\/div>\n<div dir=\"auto\">Producci\u00f3n General :<\/div>\n<div dir=\"auto\"><span class=\"html-span xdj266r x14z9mp xat24cr x1lziwak xexx8yu xyri2b x18d9i69 x1c1uobl x1hl2dhg x16tdsg8 x1vvkbs\"><a class=\"x1i10hfl xjbqb8w x1ejq31n x18oe1m7 x1sy0etr xstzfhl x972fbf x10w94by x1qhh985 x14e42zd x9f619 x1ypdohk xt0psk2 x3ct3a4 xdj266r x14z9mp xat24cr x1lziwak xexx8yu xyri2b x18d9i69 x1c1uobl x16tdsg8 x1hl2dhg xggy1nq x1a2a7pz xkrqix3 x1sur9pj x1fey0fg x1s688f\" tabindex=\"0\" role=\"link\" href=\"https:\/\/www.facebook.com\/sebastiansoler6?__cft__[0]=AZaPd9hxTOgmUB_xM53IDk_0e5mHA7UDH3clWhunOxRUOh6Fj-YWsOtvHT4NNfLDtZqq3IgJ3xOLSSyAZi_jcuQATPRYLW2LUbWvNmlwwpx-NICE9RpqNUuy4Ph_FgRpwLsMKnrNQ58eDlaH-A39KaHXqC6TLEbw29dJwfPLScYnTll8LW1le84u8rGtWiQLk9w&amp;__tn__=-]K-R\"><span class=\"xt0psk2\"><span class=\"xjp7ctv\">Sebastian Soler<\/span><\/span><\/a><\/span><\/div>\n","protected":false},"excerpt":{"rendered":"<p>En una nueva edici\u00f3n del programa \u201cVoces Callejeras\u201d, Estefan\u00eda Arce, licenciada en Nutrici\u00f3n y propietaria de Goya Grow, visit\u00f3 el estudio para compartir su experiencia en el mundo del cannabis medicinal, el crecimiento de su emprendimiento y la importancia de la informaci\u00f3n y la concientizaci\u00f3n sobre el uso responsable de la planta. Durante la entrevista, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":33835,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[74],"tags":[],"class_list":["post-33832","post","type-post","status-publish","format-standard","has-post-thumbnail","category-bitacora-tv"],"_links":{"self":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/posts\/33832","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/comments?post=33832"}],"version-history":[{"count":0,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/posts\/33832\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/media\/33835"}],"wp:attachment":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/media?parent=33832"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/categories?post=33832"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/tags?post=33832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}