{"id":36640,"date":"2026-09-02T09:18:53","date_gmt":"2026-09-02T12:18:53","guid":{"rendered":"https:\/\/radiobitacora.com.ar\/web\/?p=36640"},"modified":"2026-09-02T09:18:53","modified_gmt":"2026-09-02T12:18:53","slug":"sin-telepase-el-peaje-chaco-corrientes-costara-un-50-mas-como-tramitarlo","status":"publish","type":"post","link":"https:\/\/radiobitacora.com.ar\/web\/2026\/09\/02\/sin-telepase-el-peaje-chaco-corrientes-costara-un-50-mas-como-tramitarlo\/","title":{"rendered":"Sin TelePase, el peaje Chaco-Corrientes costar\u00e1 un 50% m\u00e1s: c\u00f3mo tramitarlo"},"content":{"rendered":"<p><strong>A partir de octubre <\/strong>comenzar\u00e1 a regir un\u00a0<strong>nuevo cuadro tarifario en el peaje\u00a0<\/strong>del corredor\u00a0<strong>Chaco-Corrientes\u00a0<\/strong>bajo la \u00f3rbita de las\u00a0<strong>nuevas concesiones viales<\/strong>. Adem\u00e1s, se inform\u00f3\u00a0<strong>que quienes no est\u00e9n adheridos\u00a0al TelePase\u00a0<\/strong>pagar\u00e1n un\u00a0<strong>recargo del 50%<\/strong>.<\/p>\n<p>El\u00a0<strong>director\u00a0<\/strong>del\u00a0<strong>Distrito Corrientes de Vialidad Nacional<\/strong>, David Oscar Moulin, confirm\u00f3 que los\u00a0<strong>veh\u00edculos livianos\u00a0<\/strong>con\u00a0<strong>TelePase\u00a0<\/strong>abonar\u00e1n una\u00a0<strong>tarifa\u00a0<\/strong>cercana a los\u00a0<strong>$1.800<\/strong>.<\/p>\n<p>Por otro lado,\u00a0<strong>quienes no utilicen la oblea electr\u00f3nica\u00a0<\/strong>y mantengan el\u00a0<strong>pago manual\u00a0<\/strong>en cabina deber\u00e1n abonar un\u00a0<strong>recargo del 50 %<\/strong>, llevando la tarifa a\u00a0<strong>$2.700\u00a0<\/strong>por pasada.<\/p>\n<h2 class=\"h2\">Tarifas diferenciadas desde octubre<\/h2>\n<p>El\u00a0<strong>nuevo esquema\u00a0<\/strong>busca\u00a0<strong>desincentivar el cobro manual\u00a0<\/strong>e imponer el pago autom\u00e1tico. Los autom\u00f3viles y veh\u00edculos livianos que cuenten con el\u00a0<strong>dispositivo electr\u00f3nico\u00a0<\/strong>abonar\u00e1n una\u00a0<strong>tarifa estimada en $1.800<\/strong>.<\/p>\n<p>De no usar el sistema autom\u00e1tico se cobrar\u00e1 un\u00a0<strong>recargo del 50 % sobre el valor base<\/strong>, abonando $2.700 por pasada.<\/p>\n<p>La actualizaci\u00f3n\u00a0<strong>aplica\u00a0<\/strong>tanto a la estaci\u00f3n del\u00a0<strong>puente Chaco-Corrientes\u00a0<\/strong>como a\u00a0<strong>todos los peajes que utilicen Telepase.<\/strong><\/p>\n<h2 class=\"h2\">C\u00f3mo realizar la adhesi\u00f3n gratuita a TelePase<\/h2>\n<p>El\u00a0<strong>tr\u00e1mite\u00a0<\/strong>para incorporar el\u00a0<strong>dispositivo electr\u00f3nico\u00a0<\/strong>se realiza de forma\u00a0<strong>100 % digital y gratuita<\/strong><\/p>\n<p>Los automovilistas deben ingresar al\u00a0<a class=\"link\" href=\"https:\/\/telepase.com.ar\/\" target=\"_blank\" rel=\"noopener\"><strong>sitio oficial de TelePase<\/strong><\/a>, cargar la\u00a0<strong>patente del veh\u00edculo\u00a0<\/strong>y vincular un\u00a0<strong>medio de pago\u00a0<\/strong>(tarjeta de cr\u00e9dito, d\u00e9bito o billetera virtual).<\/p>\n<p>El\u00a0<strong>sticker chip\u00a0<\/strong>o\u00a0<strong>TAG\u00a0<\/strong>se coloca en el\u00a0<strong>parabrisas<\/strong>. La adhesi\u00f3n al servicio no tiene costo.<\/p>\n<p>Con respecto al TAG, si se lo retira\u00a0en los\u00a0<strong>puntos presenciales habilitados\u00a0<\/strong>es\u00a0<strong>gratuito<\/strong>, aunque la\u00a0<strong>opci\u00f3n de env\u00edo a domicilio\u00a0<\/strong>puede tener un\u00a0<strong>costo de correo<\/strong>.<\/p>\n<p>Cabe mencionar que el\u00a0<strong>sticker chip sirve para circular por todas las autopistas\u00a0<\/strong>y\u00a0<strong>rutas\u00a0<\/strong>concesionadas del pa\u00eds\u00a0<strong>adheridas a la red<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A partir de octubre comenzar\u00e1 a regir un\u00a0nuevo cuadro tarifario en el peaje\u00a0del corredor\u00a0Chaco-Corrientes\u00a0bajo la \u00f3rbita de las\u00a0nuevas concesiones viales. Adem\u00e1s, se inform\u00f3\u00a0que quienes no est\u00e9n adheridos\u00a0al TelePase\u00a0pagar\u00e1n un\u00a0recargo del 50%. El\u00a0director\u00a0del\u00a0Distrito Corrientes de Vialidad Nacional, David Oscar Moulin, confirm\u00f3 que los\u00a0veh\u00edculos livianos\u00a0con\u00a0TelePase\u00a0abonar\u00e1n una\u00a0tarifa\u00a0cercana a los\u00a0$1.800. Por otro lado,\u00a0quienes no utilicen la oblea electr\u00f3nica\u00a0y mantengan [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":36641,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[72],"tags":[],"class_list":["post-36640","post","type-post","status-publish","format-standard","has-post-thumbnail","category-provinciales"],"_links":{"self":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/posts\/36640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/comments?post=36640"}],"version-history":[{"count":1,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/posts\/36640\/revisions"}],"predecessor-version":[{"id":36642,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/posts\/36640\/revisions\/36642"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/media\/36641"}],"wp:attachment":[{"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/media?parent=36640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/categories?post=36640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiobitacora.com.ar\/web\/wp-json\/wp\/v2\/tags?post=36640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}